{"id":3034,"date":"2018-06-26T09:15:47","date_gmt":"2018-06-26T15:15:47","guid":{"rendered":"https:\/\/2018.sanjose.wordcamp.org\/?p=3034"},"modified":"2018-06-26T09:15:47","modified_gmt":"2018-06-26T15:15:47","slug":"react-js","status":"publish","type":"post","link":"https:\/\/sanjose.wordcamp.org\/2018\/react-js\/","title":{"rendered":"React.js"},"content":{"rendered":"<p>React es una biblioteca Javascript de c\u00f3digo abierto para crear interfaces de usuario con el objetivo de animar al desarrollo de aplicaciones en una sola p\u00e1gina.<\/p>\n<p>En el pr\u00f3ximo WordCamp SJ 2018, tendremos un taller de Introducci\u00f3n a React en el vamos a entender los elementos fundamentales de React y como utilizarlos en el desarrollo de una aplicaci\u00f3n web. El taller ser\u00e1 impartido por <a href=\"https:\/\/2018.sanjose.wordcamp.org\/speaker\/alfredo-bonilla\/#more-1693\">Alfredo Bonilla\u00a0<\/a>\u00a0 y no te lo puedes perder.<\/p>\n<h2>Temario:<\/h2>\n<ul>\n<li>\u00bfQu\u00e9 es un componente de React?<\/li>\n<li>Componentes de clase y componentes funcionales<\/li>\n<li>JSX<\/li>\n<li>State<\/li>\n<li>Manejo de eventos.<\/li>\n<li>Props<\/li>\n<li>Buenas pr\u00e1cticas<\/li>\n<\/ul>\n<h2>Requisitos:<\/h2>\n<ul>\n<li>Entrada al WordCamp SJ 2018 <a href=\"https:\/\/2018.sanjose.wordcamp.org\/tickets\/\">(comprar aqu\u00ed)<\/a><\/li>\n<li>Conocimientos b\u00e1sicos de HTML, CSS, JS y WordPress.<\/li>\n<li>Computadora port\u00e1til. Cada asistente es responsable de cuidar su equipo para trabajar en el taller.<\/li>\n<\/ul>\n<h2>Instructor:<\/h2>\n<p><a href=\"https:\/\/2018.sanjose.wordcamp.org\/speaker\/alfredo-bonilla\/#more-1693\"><strong>Alfredo Bonilla<\/strong><\/a><\/p>\n<h2>Horario:<\/h2>\n<p>Domingo 22 de Julio 1:30pm a 3:30pm.<\/p>\n<h2>Costo<\/h2>\n<p>$10 por persona<\/p>\n<p><a href=\"https:\/\/2018.sanjose.wordcamp.org\/talleres\/\">Clic aqu\u00ed para adquirir una entrada<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>React es una biblioteca Javascript de c\u00f3digo abierto para crear interfaces de usuario con el objetivo de animar al desarrollo de aplicaciones en una sola p\u00e1gina. En el pr\u00f3ximo WordCamp SJ 2018, tendremos un taller de Introducci\u00f3n a React en el vamos a entender los elementos fundamentales de React y como utilizarlos en el desarrollo &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/sanjose.wordcamp.org\/2018\/react-js\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abReact.js\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15079632,"featured_media":3035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1241573,272,997976,34220,1241543],"class_list":["post-3034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-alfredo-bonilla","tag-javascript","tag-react","tag-taller","tag-wordcamp-san-jose-2018"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLBA-MW","jetpack-related-posts":[{"id":2950,"url":"https:\/\/sanjose.wordcamp.org\/2018\/js-para-wordpress\/","url_meta":{"origin":3034,"position":0},"title":"JS para WordPress","author":"Lidia Arroyo Vargas","date":"junio 22, 2018","format":false,"excerpt":"Existen varias maneras de insertar javascript en WordPress, pero no todas son correctas.\u00a0 Este a\u00f1o en el WordCamp SJ, Elio Rivero impartir\u00e1 un Taller Javascript para WordPress. Temario: Introducci\u00f3n al lenguaje JavaScript, tipos y estructura de datos. Como trabajar con JavaScript en WordPress (que scripts incluye, backbone, jquery, underscore...) Creando\u2026","rel":"","context":"En \u00abElio Rivero\u00bb","block_context":{"text":"Elio Rivero","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/elio-rivero\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/JS.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/JS.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/JS.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/JS.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/JS.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3081,"url":"https:\/\/sanjose.wordcamp.org\/2018\/prototipado-con-figma\/","url_meta":{"origin":3034,"position":1},"title":"Prototipado con Figma","author":"Lidia Arroyo Vargas","date":"junio 27, 2018","format":false,"excerpt":"Figma es una aplicaci\u00f3n para hacer UI, que busca competir con Sketch \u00f3 con Adobe XD. Su principal objetivo es que seamos capaces de desarrollar interfaces de usuario dentro del navegador, sin tener que acudir a software nativo. Ofrece una gran interfaz de usuario, es muy rapida, tiene infinidad de\u2026","rel":"","context":"En \u00abAllan Esquivel\u00bb","block_context":{"text":"Allan Esquivel","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/allan-esquivel\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/figma.jpg?fit=1200%2C926&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/figma.jpg?fit=1200%2C926&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/figma.jpg?fit=1200%2C926&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/figma.jpg?fit=1200%2C926&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/figma.jpg?fit=1200%2C926&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2580,"url":"https:\/\/sanjose.wordcamp.org\/2018\/taller-design-thinking-post\/","url_meta":{"origin":3034,"position":2},"title":"Design Thinking","author":"Lidia Arroyo Vargas","date":"junio 14, 2018","format":false,"excerpt":"El Design Thinking es un m\u00e9todo para generar ideas innovadoras que centra su eficacia en entender y dar soluci\u00f3n a las necesidades reales de los usuarios. Grandes empresas como Apple y Google lo utilizan. Al ser un gran generador de innovaci\u00f3n, se puede aplicar a cualquier campo. En el WordCamp\u2026","rel":"","context":"En \u00abdesign thinking\u00bb","block_context":{"text":"design thinking","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/design-thinking\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/35244518_472347109869520_8671113979315093504_n1.jpg?fit=960%2C718&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/35244518_472347109869520_8671113979315093504_n1.jpg?fit=960%2C718&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/35244518_472347109869520_8671113979315093504_n1.jpg?fit=960%2C718&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/35244518_472347109869520_8671113979315093504_n1.jpg?fit=960%2C718&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2602,"url":"https:\/\/sanjose.wordcamp.org\/2018\/taller-impulsando-ventas-woocommerce-e-inteligencia-artificial-post\/","url_meta":{"origin":3034,"position":3},"title":"Impulsando ventas WooCommerce e inteligencia artificial","author":"Lidia Arroyo Vargas","date":"junio 14, 2018","format":false,"excerpt":"WooCommerce es un plugin gratuito de eCommerce que nos permite vender cualquier cosa con mucha elegancia. Fernando Tellado\u00a0 impartir\u00e1 en\u00a0 el WordCamp SJ 2018 un taller de WooCommerce\u00a0 donde puedes aprender a crear desde cero, paso a paso y en riguroso directo, una tienda online para vender productos f\u00edsicos y\u2026","rel":"","context":"En \u00abFernando Tellado\u00bb","block_context":{"text":"Fernando Tellado","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/fernando-tellado\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/woocommerce.png?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/woocommerce.png?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/woocommerce.png?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/woocommerce.png?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/woocommerce.png?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3011,"url":"https:\/\/sanjose.wordcamp.org\/2018\/no-te-pierdas-de-la-charla-y-el-taller-de-elio-rivero-este-21-y-22-de-julio-en-el-wordcamp-san-jose\/","url_meta":{"origin":3034,"position":4},"title":"No te pierdas de la charla y el taller de Elio Rivero este 21 y 22 de julio en el WordCamp San Jos\u00e9","author":"Krysia Castillo","date":"junio 25, 2018","format":"video","excerpt":"","rel":"","context":"En \u00abElio Rivero\u00bb","block_context":{"text":"Elio Rivero","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/elio-rivero\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/cropped-tixAsset-4.png?fit=600%2C600&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":2718,"url":"https:\/\/sanjose.wordcamp.org\/2018\/ux-para-principiantes\/","url_meta":{"origin":3034,"position":5},"title":"UX para principiantes","author":"Lidia Arroyo Vargas","date":"junio 20, 2018","format":false,"excerpt":"\u00bfQu\u00e9 es UX? UX (por sus siglas en ingl\u00e9s User eXperience) o en espa\u00f1ol Experiencia de Usuario. Es aquello que una persona percibe al interactuar con un producto \u00f3 servicio. Este a\u00f1o en el WordCamp SJ tendremos un taller de UX para principiantes, a cargo de Nathalie Howell-Flores y Gretchen\u2026","rel":"","context":"En \u00abGretchen Hutt\u00bb","block_context":{"text":"Gretchen Hutt","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/gretchen-hutt\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/UX.png?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/UX.png?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/UX.png?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/UX.png?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/UX.png?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/react.jpg?fit=1200%2C900&ssl=1","_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/3034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15079632"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=3034"}],"version-history":[{"count":1,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/3034\/revisions"}],"predecessor-version":[{"id":3036,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/3034\/revisions\/3036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/3035"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=3034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=3034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=3034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}