{"id":2504,"date":"2018-06-12T10:00:32","date_gmt":"2018-06-12T16:00:32","guid":{"rendered":"https:\/\/2018.sanjose.wordcamp.org\/?p=2504"},"modified":"2018-06-11T21:55:51","modified_gmt":"2018-06-12T03:55:51","slug":"gold-sponsor-accenture","status":"publish","type":"post","link":"https:\/\/sanjose.wordcamp.org\/2018\/gold-sponsor-accenture\/","title":{"rendered":"Gold Sponsor &#8211; Accenture"},"content":{"rendered":"<p>Innovaci\u00f3n y talento. <strong>Accenture<\/strong>, es un lugar donde se ayuda a mejorar la forma en la que el mundo vive y trabaja.<\/p>\n<p><strong>Accenture<\/strong> cuenta con cinco \u00e1reas de negocio que combinadas para transformar y\u00a0 crecer con sus clientes: Accenture Strategy, Accenture Consulting, Accenture Digital, Accenture Technology y Accenture Operations. Cada uno demanda un perfil diferente, con planes de carrera que se ajustan a tus necesidades, pero siempre con la identidad de Accenture: ayudar a crecer y a desarrollarte profesional y tambi\u00e9n personalmente.<\/p>\n<p>No hay un llanero solitario, sino trabajo en equipo. Y Accenture quiere\u00a0 que cada uno se convierta en un jugador.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1516\" data-permalink=\"https:\/\/sanjose.wordcamp.org\/2018\/sponsor\/accenture\/accenturewcsj18\/\" data-orig-file=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/accentureWCSJ18.png?fit=720%2C176&amp;ssl=1\" data-orig-size=\"720,176\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"accentureWCSJ18\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;accentureWCSJ18&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/accentureWCSJ18.png?fit=525%2C128&amp;ssl=1\" class=\"size-medium wp-image-1516 aligncenter\" src=\"https:\/\/i0.wp.com\/2018.sanjose.wordcamp.org\/files\/2018\/05\/accentureWCSJ18-300x73.png?resize=300%2C73&#038;ssl=1\" alt=\"accentureWCSJ18\" width=\"300\" height=\"73\" srcset=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/accentureWCSJ18.png?resize=300%2C73&amp;ssl=1 300w, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/accentureWCSJ18.png?resize=500%2C122&amp;ssl=1 500w, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/accentureWCSJ18.png?w=720&amp;ssl=1 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Durante todos estos a\u00f1os han participado en las principales operaciones de fusiones y adquisiciones, en los procesos de internacionalizaci\u00f3n m\u00e1s ambiciosos y en las estrategias de transformaci\u00f3n tecnol\u00f3gicas m\u00e1s complejas.<\/p>\n<p>Ahora lideran la transformaci\u00f3n digital de sus clientes. Ma\u00f1ana ser\u00e1 la combinaci\u00f3n de servicios digitales, servicios Cloud y servicios de seguridad, entre otros.<\/p>\n<p>\u00c9ste es el nuevo mundo que est\u00e1 por llegar y que Accenture est\u00e1 definiendo. \u00bfQuieres crearlo con Accenturo o esperar a seguirlo en otras organizaciones? Vos decides, no ponga l\u00edmites a su imaginaci\u00f3n y antic\u00edpate. Es apasionante.<\/p>\n<p>M\u00e1s informaci\u00f3n en:<br \/>\n<a href=\"http:\/\/www.incorporate.accenture.com\">www.incorporate.accenture.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Innovaci\u00f3n y talento. Accenture, es un lugar donde se ayuda a mejorar la forma en la que el mundo vive y trabaja. Accenture cuenta con cinco \u00e1reas de negocio que combinadas para transformar y\u00a0 crecer con sus clientes: Accenture Strategy, Accenture Consulting, Accenture Digital, Accenture Technology y Accenture Operations. Cada uno demanda un perfil diferente, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/sanjose.wordcamp.org\/2018\/gold-sponsor-accenture\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abGold Sponsor &#8211; Accenture\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15514800,"featured_media":1514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[1241540,1241541,8328],"class_list":["post-2504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-accenture","tag-accenture-costa-rica","tag-gold-sponsor"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLBA-Eo","jetpack-related-posts":[{"id":4165,"url":"https:\/\/sanjose.wordcamp.org\/2018\/muchas-gracias-por-ser-parte-del-wordcamp-san-jose-costa-rica-2018\/","url_meta":{"origin":2504,"position":0},"title":"\u00a1Muchas gracias por ser parte del WordCamp San Jos\u00e9 Costa Rica 2018!","author":"Ericka Barboza","date":"julio 27, 2018","format":"image","excerpt":"\u00a1Un fin de semana de WordPress fant\u00e1stico! El WordCamp San Jos\u00e9 Costa Rica #WCSJ fue todo un \u00e9xito, vendimos todas las entradas, \u00a1600 asistentes!, puede decirse que el doble de asistentes del a\u00f1o pasado, una meta sobrepasada y por mucho. El comit\u00e9 organizador compuesto de 5 mujeres (WordCamp Girls, \u00a1Girl\u2026","rel":"","context":"Con 3 comentarios","block_context":{"text":"Con 3 comentarios","link":"https:\/\/sanjose.wordcamp.org\/2018\/muchas-gracias-por-ser-parte-del-wordcamp-san-jose-costa-rica-2018\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1247,"url":"https:\/\/sanjose.wordcamp.org\/2018\/gold-sponsor-siteground\/","url_meta":{"origin":2504,"position":1},"title":"GOLD Sponsor SiteGround","author":"Giancarlos Villalobos","date":"abril 13, 2018","format":false,"excerpt":"Fundada en 2004 por unos amigos de la Universidad, SiteGround poco a poco, se ha convertido en un proveedor de servicios de alojamiento web l\u00edder en el sector. Con s\u00f3lo un peque\u00f1o grupo de personas trabajando desde sus dormitorios universitarios en sus inicios, hoy la empresa tiene alrededor de 400\u2026","rel":"","context":"En \u00abHosting\u00bb","block_context":{"text":"Hosting","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/hosting\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1464,"url":"https:\/\/sanjose.wordcamp.org\/2018\/gold-sponsor-konrad-group\/","url_meta":{"origin":2504,"position":2},"title":"Gold Sponsor &#8211; Konrad Group","author":"Giancarlos Villalobos","date":"mayo 14, 2018","format":false,"excerpt":"Konrad es una importante agencia digital, la cual nos acompa\u00f1a por segunda ocasi\u00f3n como patrocinador del WordCamp San Jos\u00e9 Costa Rica,\u00a0 Konrad\u00a0ayuda empresas y marcas a triunfar en la era digital. \"Ayudamos a nuestros clientes a identificar, planificar y aprovechar las oportunidades digitales donde sea que se encuentren. Con una\u2026","rel":"","context":"En \u00abGold Sponsor\u00bb","block_context":{"text":"Gold Sponsor","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/gold-sponsor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/2018.sanjose.wordcamp.org\/files\/2018\/04\/konrad-logo-wcsj-300x72.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1610,"url":"https:\/\/sanjose.wordcamp.org\/2018\/gold-sponsor-brainstation\/","url_meta":{"origin":2504,"position":3},"title":"Gold Sponsor BrainStation","author":"Lidia Arroyo Vargas","date":"mayo 18, 2018","format":false,"excerpt":"BrainStation es una academia con sedes en San Jos\u00e9,\u00a0New York,\u00a0 Toronto y Vancouver, que \"fomenta la nueva generaci\u00f3n de creadores\" mediante cursos y talleres enfocados en proyectos, con recursos, curr\u00edculums desarrollados y actualizados en tiempo real con las nuevas tendencias de la industria digital. Si su objetivo es avanzar en\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/cropped-tixAsset-4.png?fit=600%2C600&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":1666,"url":"https:\/\/sanjose.wordcamp.org\/2018\/gold-sponsor-gravity\/","url_meta":{"origin":2504,"position":4},"title":"Gold Sponsor Gravity","author":"Edgar Jimenez","date":"junio 6, 2018","format":false,"excerpt":"Formularios Avanzados F\u00e1ciles de Implementar. El 24 de agosto del 2009, despu\u00e9s de varios meses de programaci\u00f3n y de pruebas en versi\u00f3n Beta, Carl Hancock Co-Fundador de Gravity, anunciaba el lanzamiento de la Versi\u00f3n 1.0 del Gravity Forms compatible con WordPress Versi\u00f3n 2.8+, siendo este el inicio de un gran\u2026","rel":"","context":"En \u00abGold Sponsor\u00bb","block_context":{"text":"Gold Sponsor","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/gold-sponsor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/cropped-tixAsset-4.png?fit=600%2C600&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":3045,"url":"https:\/\/sanjose.wordcamp.org\/2018\/elementos-esenciales-de-seguridad-para-cada-sitio-de-wordpress\/","url_meta":{"origin":2504,"position":5},"title":"Elementos esenciales de seguridad para cada sitio de WordPress","author":"Krysia Castillo","date":"junio 26, 2018","format":false,"excerpt":"Jetpack conecta su sitio con los servicios globales, la comunidad y el soporte proporcionado por WordPress. Protege autom\u00e1ticamente su sitio de la atenci\u00f3n no deseada de spammers, hackers y malware, mientras realiza sincronizaciones y copias de seguridad en tiempo real por lo que es un excelente beneficio para el usuario\u2026","rel":"","context":"En \u00abGold Sponsor\u00bb","block_context":{"text":"Gold Sponsor","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/gold-sponsor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/2018.sanjose.wordcamp.org\/files\/2018\/06\/Jetpack_Horizontal_RGB-300x83.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/Screen-Shot-2018-05-07-at-10.31.08-AM.png?fit=678%2C214&ssl=1","_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15514800"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=2504"}],"version-history":[{"count":6,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2504\/revisions"}],"predecessor-version":[{"id":2525,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2504\/revisions\/2525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/1514"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=2504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=2504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=2504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}