{"id":2311,"date":"2018-06-01T16:17:34","date_gmt":"2018-06-01T22:17:34","guid":{"rendered":"https:\/\/2018.sanjose.wordcamp.org\/?p=2311"},"modified":"2018-06-21T12:17:00","modified_gmt":"2018-06-21T18:17:00","slug":"quienes-forman-parte-de-la-comunidad-wordpress","status":"publish","type":"post","link":"https:\/\/sanjose.wordcamp.org\/2018\/quienes-forman-parte-de-la-comunidad-wordpress\/","title":{"rendered":"\u00bfQui\u00e9nes forman parte de la Comunidad WordPress?"},"content":{"rendered":"<p>Si eres usuario de WordPress t\u00fa ya eres Comunidad WordPress, no importa si eres usuario, programador, bloguero, dise\u00f1ador, desarrollador, si est\u00e1s relacionado un poco \u00f3 mucho con WordPress, eres miembro de la gran comunidad WordPress a nivel mundial.<\/p>\n<h2>Comunidad de WordPress Costa Rica<\/h2>\n<p>En Costa Rica somos m\u00e1s de mil miembros activos en redes sociales como <a href=\"https:\/\/www.facebook.com\/groups\/WordpressCR\/\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/WordCampSanJose\">Twitter<\/a>, <a href=\"https:\/\/www.instagram.com\/wordcampsanjose\/\">Instagram<\/a> y <a href=\"https:\/\/www.meetup.com\/es\/Costa-Rica-WordPress-Meetup\/events\/\">Meetup<\/a>.<\/p>\n<p>Nuestro objetivo es compartir conocimientos sobre este Administrador de Contenidos Web de Software Libre que nos permite tener una P\u00e1gina Web en minutos y con conocimientos b\u00e1sicos, permitiendo as\u00ed tener desde un blog personal hasta un negocio propio y tienda en l\u00ednea.<\/p>\n<h3>\u00bfQu\u00e9 tipo de actividades realiza la Comunidad de WordPress Costa Rica?<\/h3>\n<h4>Meetups WordPress Costa Rica<\/h4>\n<p>Realizamos charlas en universidades, empresas y escuelas, que nos colaboran prestando las instalaciones para realizar las ponencias de temas referentes a WordPress y tecnolog\u00eda, siempre de forma gratuita, los asistentes a las Meetups (como les llamamos), pueden aprender y mejorar su conocimiento con estas charlas impartidas por personas que tambi\u00e9n quieran donar sus conocimientos, todo es un esfuerzo de comunidad y de accesibilidad para todos.<\/p>\n<h4>WordCamp Costa Rica<\/h4>\n<p>El <a href=\"https:\/\/www.facebook.com\/wordcampcr\/\">WordCamp<\/a> es un evento de tecnolog\u00eda donde se re\u00fanen m\u00e1s de 300 personas, entre ellas, Dise\u00f1adores, Programadores, Bloggers, Emprendedores, Estudiantes, todos con un fin, conocer de WordPress.<\/p>\n<p>El WordCamp es un evento que conlleva un esfuerzo de muchos meses por parte de un grupo de organizadores (este a\u00f1o somos 9 organizadores) que trabaja voluntariamente para llevar el evento a cabo y que sea un \u00e9xito. Consta de dos d\u00edas completos, donde se realizan talleres, charlas con m\u00e1s de 50 expositores profesionales nacionales e internacionales, los cuales tambi\u00e9n donan su tiempo y sus conocimientos para asistir al evento, se fomenta la uni\u00f3n como comunidad para compartir el aprendizaje en el cual cada uno se especializa.<\/p>\n<p>Contamos con un grupo de <a href=\"https:\/\/2018.sanjose.wordcamp.org\/info\/sponsors\/\">patrocinadores<\/a> tanto a nivel internacional como nacional que nos apoyan para que el evento est\u00e9 completo y podamos contar con dos d\u00edas de almuerzo, caf\u00e9, snacks, regalos para todos los asistentes al congreso. Adem\u00e1s, de una actividad social que realizamos el primer d\u00eda con el fin de invitar a todos a formar parte de la gran comunidad WordPress.<\/p>\n<h4>El D\u00eda de Contribuci\u00f3n (Contributor Day WordPress)<\/h4>\n<p>WordPress es creado por miles de personas como usted, no es necesario ser programador o dise\u00f1ador para comenzar a contribuir.<\/p>\n<p>Algunas \u00e1reas en las que se puede colaborar:<\/p>\n<ul>\n<li>Revisi\u00f3n de temas: forma parte del equipo responsable de la alta calidad en el directorio de temas en <a href=\"https:\/\/wordpress.org\/\">WordPress.org<\/a>.<\/li>\n<li>WordPress.tv: revisa y aprueba cada video enviado a <a href=\"https:\/\/wordpress.tv\/\">WordPress.tv<\/a>. Tambi\u00e9n ayudan WordCamps con la postproducci\u00f3n de v\u00eddeo. Necesitamos ayudar a la edici\u00f3n de los videos de las conversaciones para que podamos subirlos a WordPress.tv.<\/li>\n<li>Docs: mejorar el Codex, manuales y otros recursos en l\u00ednea para los usuarios y desarrolladores de WordPress.<\/li>\n<li>Accesibilidad: prueba y mejorar la accesibilidad del proyecto WordPress.<\/li>\n<\/ul>\n<p>\u00bfQu\u00e9 se necesita?<\/p>\n<ul>\n<li>Computador port\u00e1til.<\/li>\n<li>Cuenta en <a href=\"https:\/\/wordpress.org\/\">wordpress.org<\/a><\/li>\n<li>Muchas ganas de colaborar.<\/li>\n<\/ul>\n<h4>D\u00eda de traducci\u00f3n de WordPress (WordPress Translation Day).<\/h4>\n<p>Es un evento de 24 horas en vivo organizado por el<a href=\"https:\/\/make.wordpress.org\/polyglots\/\"> equipo de WordPress Polyglots<\/a> , cuya misi\u00f3n es traducir WordPress en tantos idiomas como sea posible.<\/p>\n<p>Gracias a este tipo de actividades y a los m\u00e1s de 14.000 voluntarios en todo el mundo que hoy WordPress &#8211; y muchos de los elementos en su ecosistema &#8211; est\u00e1n disponibles en 169 idiomas, por lo que la plataforma de acceso a muchas personas que no hablan ingl\u00e9s.<\/p>\n<h1>Excelente. \u00a1Quiero Participar!<\/h1>\n<p>WordPress es creado por miles de personas como usted. No tiene que ser un programador o un dise\u00f1ador para comenzar a contribuir.<\/p>\n<p>Para participar en los eventos que organizamos en la Comunidad solo debes seguirnos en nuestras redes sociales:<\/p>\n<ul>\n<li>Facebook: <a href=\"https:\/\/www.facebook.com\/groups\/WordpressCR\/\">https:\/\/www.facebook.com\/groups\/WordpressCR\/<\/a> \u00a0\u00f3 <a href=\"https:\/\/www.facebook.com\/wordcampcr\/\">https:\/\/www.facebook.com\/wordcampcr\/<\/a><\/li>\n<li>Meetup: https:\/\/www.meetup.com\/es\/Costa-Rica-WordPress-Meetup\/<\/li>\n<li>Twitter: <a href=\"https:\/\/twitter.com\/WordCampSanJose\">https:\/\/twitter.com\/WordCampSanJose<\/a><\/li>\n<li>Instagram: <a href=\"https:\/\/www.instagram.com\/wordcampsanjose\/\">https:\/\/www.instagram.com\/wordcampsanjose\/<\/a><\/li>\n<\/ul>\n<p>Tambi\u00e9n puedes escribirnos al correo: <a href=\"mailto:sanjose@wordcamp.org\">sanjose@wordcamp.org<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si eres usuario de WordPress t\u00fa ya eres Comunidad WordPress, no importa si eres usuario, programador, bloguero, dise\u00f1ador, desarrollador, si est\u00e1s relacionado un poco \u00f3 mucho con WordPress, eres miembro de la gran comunidad WordPress a nivel mundial. Comunidad de WordPress Costa Rica En Costa Rica somos m\u00e1s de mil miembros activos en redes sociales &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/sanjose.wordcamp.org\/2018\/quienes-forman-parte-de-la-comunidad-wordpress\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfQui\u00e9nes forman parte de la Comunidad WordPress?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15079632,"featured_media":2313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[210961,1241564,1241543,14],"class_list":["post-2311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-comunidad","tag-meeutp","tag-wordcamp-san-jose-2018","tag-wordpress"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLBA-Bh","jetpack-related-posts":[{"id":2854,"url":"https:\/\/sanjose.wordcamp.org\/2018\/wordpress-101\/","url_meta":{"origin":2311,"position":0},"title":"WordPress 101","author":"Lidia Arroyo Vargas","date":"junio 21, 2018","format":false,"excerpt":"WordPress es un excelente sistema de gesti\u00f3n de contenidos o \u201cContent Management System\u201d (CMS). No es solo una herramienta para crear un sitio web\u00a0 es una poderosa herramienta para mantener organizada y mantenida tu presencia web a lo largo del tiempo. Este a\u00f1o en WordCamp San Jos\u00e9, impartiremos un taller\u2026","rel":"","context":"En \u00abRoberto Remedios\u00bb","block_context":{"text":"Roberto Remedios","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/roberto-remedios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":865,"url":"https:\/\/sanjose.wordcamp.org\/2018\/es-para-mi-un-wordcamp-post\/","url_meta":{"origin":2311,"position":1},"title":"\u00bfEs para m\u00ed un WordCamp?","author":"remediosgraphic","date":"marzo 13, 2018","format":false,"excerpt":"A un WordCamp puede acudir cualquier tipo de persona con un perfil relacionado con WordPress e internet. Algunas ideas de los perfiles que han acudido a los anteriores WCSJ: freelance desarrolladores, dise\u00f1adores gr\u00e1ficos\/ web, SEO, bloggers, community manager, periodistas, emprendedores, agencias de marketing, comunicaci\u00f3n, empresas de cualquier sector que quieran\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/cropped-tixAsset-4.png?fit=600%2C600&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":997,"url":"https:\/\/sanjose.wordcamp.org\/2018\/sea-patrocinador-del-wordcamp-san-jose-2018\/","url_meta":{"origin":2311,"position":2},"title":"Sea patrocinador del WordCamp San Jos\u00e9 2018","author":"Krysia Castillo","date":"marzo 20, 2018","format":false,"excerpt":"Los patrocinadores son una gran parte de cada WordCamp. Actualmente estamos buscando patrocinadores para ayudar a que WordCamp San Jos\u00e9 2018 sea lo m\u00e1s grandioso posible. Patrocinar un WordCamp ofrece la oportunidad de acercarse a un p\u00fablico comprometido, conocedor de la tecnolog\u00eda, informado e inteligente. Los asistentes a WordCamp San\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1214,"url":"https:\/\/sanjose.wordcamp.org\/2018\/woocommerce-el-exitoso-plugin-de-wordpress-para-tiendas-online\/","url_meta":{"origin":2311,"position":3},"title":"WooCommerce el exitoso plugin de WordPress para tiendas online","author":"Lidia Arroyo Vargas","date":"abril 11, 2018","format":false,"excerpt":"Lo que en el 2008 inici\u00f3 con tres entusiastas de WordPress de diferentes pa\u00edses que compart\u00edan ideas por correo electr\u00f3nico, ahora es un equipo internacional de dise\u00f1adores, desarrolladores, soporte y personal de marketing, que atienden a una comunidad apasionada y en constante crecimiento de cientos de miles de usuarios. \u00bfQu\u00e9\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/cropped-tixAsset-4.png?fit=600%2C600&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":974,"url":"https:\/\/sanjose.wordcamp.org\/2018\/buscamos-a-los-mejores-speakers\/","url_meta":{"origin":2311,"position":4},"title":"\u00a1Buscamos a los mejores SPEAKERS!","author":"Krysia Castillo","date":"marzo 19, 2018","format":"image","excerpt":"En el Wordcamp San Jos\u00e9 2018 que se llevar\u00e1 a cabo los d\u00edas 21 y 22 de julio necesitamos contar con los mejores expositores y contigo es posible. Es nuestro tercer WordCamp y queremos seguir cosechando \u00e9xitos y buenas experiencias. \u00bf Tienes un tema que la comunidad de WordPress e\u2026","rel":"","context":"Con 2 comentarios","block_context":{"text":"Con 2 comentarios","link":"https:\/\/sanjose.wordcamp.org\/2018\/buscamos-a-los-mejores-speakers\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/speaker.png?fit=1200%2C901&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/speaker.png?fit=1200%2C901&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/speaker.png?fit=1200%2C901&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/speaker.png?fit=1200%2C901&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/speaker.png?fit=1200%2C901&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4165,"url":"https:\/\/sanjose.wordcamp.org\/2018\/muchas-gracias-por-ser-parte-del-wordcamp-san-jose-costa-rica-2018\/","url_meta":{"origin":2311,"position":5},"title":"\u00a1Muchas gracias por ser parte del WordCamp San Jos\u00e9 Costa Rica 2018!","author":"Ericka Barboza","date":"julio 27, 2018","format":"image","excerpt":"\u00a1Un fin de semana de WordPress fant\u00e1stico! El WordCamp San Jos\u00e9 Costa Rica #WCSJ fue todo un \u00e9xito, vendimos todas las entradas, \u00a1600 asistentes!, puede decirse que el doble de asistentes del a\u00f1o pasado, una meta sobrepasada y por mucho. El comit\u00e9 organizador compuesto de 5 mujeres (WordCamp Girls, \u00a1Girl\u2026","rel":"","context":"Con 3 comentarios","block_context":{"text":"Con 3 comentarios","link":"https:\/\/sanjose.wordcamp.org\/2018\/muchas-gracias-por-ser-parte-del-wordcamp-san-jose-costa-rica-2018\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/camp2017.jpg?fit=2000%2C1333&ssl=1","_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15079632"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=2311"}],"version-history":[{"count":3,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2311\/revisions"}],"predecessor-version":[{"id":2316,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2311\/revisions\/2316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/2313"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=2311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=2311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=2311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}