{"id":1518,"date":"2018-05-16T09:53:10","date_gmt":"2018-05-16T15:53:10","guid":{"rendered":"https:\/\/2018.sanjose.wordcamp.org\/?p=1518"},"modified":"2018-05-16T09:53:10","modified_gmt":"2018-05-16T15:53:10","slug":"bluehost-proveedor-de-alojamiento-y-soluciones-web","status":"publish","type":"post","link":"https:\/\/sanjose.wordcamp.org\/2018\/bluehost-proveedor-de-alojamiento-y-soluciones-web\/","title":{"rendered":"Bluehost: proveedor de alojamiento y soluciones web"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1519\" data-permalink=\"https:\/\/sanjose.wordcamp.org\/2018\/bluehost-proveedor-de-alojamiento-y-soluciones-web\/bluehost_main_logo\/\" data-orig-file=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/bluehost_main_logo.png?fit=2690%2C739&amp;ssl=1\" data-orig-size=\"2690,739\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bluehost_main_logo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/05\/bluehost_main_logo.png?fit=525%2C144&amp;ssl=1\" class=\"aligncenter wp-image-1519\" src=\"https:\/\/i0.wp.com\/2018.sanjose.wordcamp.org\/files\/2018\/05\/bluehost_main_logo-300x82.png?resize=320%2C98&#038;ssl=1\" alt=\"\" width=\"320\" height=\"98\" \/><\/p>\n<p><strong>Bluehost<\/strong> fue fundado por Matt Heaton y Danny Ashword, \u00a0socio de WordPress hace m\u00e1s de 10 a\u00f1os. Cuenta con un equipo dedicado exclusivamente a la plataforma para un mejor soporte, las <strong>24<\/strong> horas del d\u00eda y los <strong>7<\/strong> d\u00edas de la semana.<\/p>\n<p>Brinda soluciones web dise\u00f1adas para satisfacer las necesidades de cada cliente, promover la cortes\u00eda de la web y fomentar un lugar seguro donde las personas principiantes o profesionales puedan aprovechar al m\u00e1ximo la red.<\/p>\n<p>Ha innovado continuamente e integrado en cada cuenta <strong>Bluehost<\/strong>, los recursos complementarios para mejorar la capacidad, la seguridad, velocidad y funcionalidad de cada sitio.<\/p>\n<p>Entre los servicios que ofrecen est\u00e1n:<\/p>\n<ul>\n<li>El alojamiento web compartido<\/li>\n<li>Alojamiento web en la nube<\/li>\n<li>WordPress hosting<\/li>\n<li>Alojamiento WooCommerce<\/li>\n<li>Alojamiento VPS de pr\u00f3xima generaci\u00f3n<\/li>\n<li>Hosting dedicado para el rendimiento, seguridad y control del sitio web.<\/li>\n<li>Dominios<\/li>\n<li>Red de apoyo 24\/7<\/li>\n<\/ul>\n<p>Este a\u00f1o <strong>Bluehost<\/strong> \u00a0ser\u00e1 patrocinador \u00a0del \u00a0<strong>WordCamp San Jos\u00e9, Costa Rica <\/strong>por lo que los invitamos a este evento a conocer m\u00e1s de nuestros patrocinadores, adem\u00e1s de excelentes charlas por parte de nuestros expositores.<strong><br \/>\n<\/strong><\/p>\n<p>Conoc\u00e9 m\u00e1s de <strong>Bluehost<\/strong> en su sitio:<br \/>\n<a href=\"https:\/\/www.bluehost.com\/\" rel=\"nofollow\">https:\/\/www.bluehost.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bluehost fue fundado por Matt Heaton y Danny Ashword, \u00a0socio de WordPress hace m\u00e1s de 10 a\u00f1os. Cuenta con un equipo dedicado exclusivamente a la plataforma para un mejor soporte, las 24 horas del d\u00eda y los 7 d\u00edas de la semana. Brinda soluciones web dise\u00f1adas para satisfacer las necesidades de cada cliente, promover la &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/sanjose.wordcamp.org\/2018\/bluehost-proveedor-de-alojamiento-y-soluciones-web\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abBluehost: proveedor de alojamiento y soluciones web\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15529066,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1518","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLBA-ou","jetpack-related-posts":[{"id":1524,"url":"https:\/\/sanjose.wordcamp.org\/2018\/dreamhost-alojamiento-web-simplificado-y-confiable\/","url_meta":{"origin":1518,"position":0},"title":"Dreamhost: alojamiento web simplificado y confiable","author":"Krysia Castillo","date":"mayo 21, 2018","format":false,"excerpt":"Dreamhost cuenta con casi 20 a\u00f1os de experiencia en hosting y se enfocan en sitios exitosos para dise\u00f1adores web, desarrolladores, bloggers y negocios en l\u00edneas. Desde 1997, han ayudan a fomentar el \u00e9xito al proporcionar una plataforma web abierta de elecci\u00f3n, actualmente su n\u00famero de clientes ha crecido a m\u00e1s\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/2018.sanjose.wordcamp.org\/files\/2018\/05\/descarga-300x82.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2854,"url":"https:\/\/sanjose.wordcamp.org\/2018\/wordpress-101\/","url_meta":{"origin":1518,"position":1},"title":"WordPress 101","author":"Lidia Arroyo Vargas","date":"junio 21, 2018","format":false,"excerpt":"WordPress es un excelente sistema de gesti\u00f3n de contenidos o \u201cContent Management System\u201d (CMS). No es solo una herramienta para crear un sitio web\u00a0 es una poderosa herramienta para mantener organizada y mantenida tu presencia web a lo largo del tiempo. Este a\u00f1o en WordCamp San Jos\u00e9, impartiremos un taller\u2026","rel":"","context":"En \u00abRoberto Remedios\u00bb","block_context":{"text":"Roberto Remedios","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/roberto-remedios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/WP101.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2680,"url":"https:\/\/sanjose.wordcamp.org\/2018\/be-green-with-greengeeks\/","url_meta":{"origin":1518,"position":2},"title":"Be Green with GreenGeeks","author":"Ericka Barboza","date":"junio 19, 2018","format":false,"excerpt":"GreenGeeks es un proveedor de hosting que desde su lanzamiento en el 2008 ha sido el l\u00edder de alojamiento web respetuoso con el medio ambiente, siendo as\u00ed, que para el a\u00f1o 2009 La Agencia de Protecci\u00f3n del Medio Ambiente de Estados Unidos (US EPA), encargada de proteger la salud humana\u2026","rel":"","context":"En \u00abBronze Sponsor\u00bb","block_context":{"text":"Bronze Sponsor","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/bronze-sponsor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/2017-GreenGeeks-logo-CMYK-black-type-JPEG.jpg?fit=1200%2C258&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/2017-GreenGeeks-logo-CMYK-black-type-JPEG.jpg?fit=1200%2C258&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/2017-GreenGeeks-logo-CMYK-black-type-JPEG.jpg?fit=1200%2C258&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/2017-GreenGeeks-logo-CMYK-black-type-JPEG.jpg?fit=1200%2C258&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/06\/2017-GreenGeeks-logo-CMYK-black-type-JPEG.jpg?fit=1200%2C258&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1247,"url":"https:\/\/sanjose.wordcamp.org\/2018\/gold-sponsor-siteground\/","url_meta":{"origin":1518,"position":3},"title":"GOLD Sponsor SiteGround","author":"Giancarlos Villalobos","date":"abril 13, 2018","format":false,"excerpt":"Fundada en 2004 por unos amigos de la Universidad, SiteGround poco a poco, se ha convertido en un proveedor de servicios de alojamiento web l\u00edder en el sector. Con s\u00f3lo un peque\u00f1o grupo de personas trabajando desde sus dormitorios universitarios en sus inicios, hoy la empresa tiene alrededor de 400\u2026","rel":"","context":"En \u00abHosting\u00bb","block_context":{"text":"Hosting","link":"https:\/\/sanjose.wordcamp.org\/2018\/tag\/hosting\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/04\/siteground.png?fit=1000%2C244&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":997,"url":"https:\/\/sanjose.wordcamp.org\/2018\/sea-patrocinador-del-wordcamp-san-jose-2018\/","url_meta":{"origin":1518,"position":4},"title":"Sea patrocinador del WordCamp San Jos\u00e9 2018","author":"Krysia Castillo","date":"marzo 20, 2018","format":false,"excerpt":"Los patrocinadores son una gran parte de cada WordCamp. Actualmente estamos buscando patrocinadores para ayudar a que WordCamp San Jos\u00e9 2018 sea lo m\u00e1s grandioso posible. Patrocinar un WordCamp ofrece la oportunidad de acercarse a un p\u00fablico comprometido, conocedor de la tecnolog\u00eda, informado e inteligente. Los asistentes a WordCamp San\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/03\/sponsor.png?fit=1200%2C898&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4165,"url":"https:\/\/sanjose.wordcamp.org\/2018\/muchas-gracias-por-ser-parte-del-wordcamp-san-jose-costa-rica-2018\/","url_meta":{"origin":1518,"position":5},"title":"\u00a1Muchas gracias por ser parte del WordCamp San Jos\u00e9 Costa Rica 2018!","author":"Ericka Barboza","date":"julio 27, 2018","format":"image","excerpt":"\u00a1Un fin de semana de WordPress fant\u00e1stico! El WordCamp San Jos\u00e9 Costa Rica #WCSJ fue todo un \u00e9xito, vendimos todas las entradas, \u00a1600 asistentes!, puede decirse que el doble de asistentes del a\u00f1o pasado, una meta sobrepasada y por mucho. El comit\u00e9 organizador compuesto de 5 mujeres (WordCamp Girls, \u00a1Girl\u2026","rel":"","context":"Con 3 comentarios","block_context":{"text":"Con 3 comentarios","link":"https:\/\/sanjose.wordcamp.org\/2018\/muchas-gracias-por-ser-parte-del-wordcamp-san-jose-costa-rica-2018\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2018\/files\/2018\/07\/MUCHAS-GRACIAS.png?fit=1200%2C448&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15529066"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1518"}],"version-history":[{"count":2,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1518\/revisions"}],"predecessor-version":[{"id":1604,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1518\/revisions\/1604"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}