{"id":1013,"date":"2017-07-20T23:43:43","date_gmt":"2017-07-20T23:43:43","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_sponsor&#038;p=1013"},"modified":"2017-08-03T02:16:48","modified_gmt":"2017-08-03T02:16:48","slug":"ex2outcoding","status":"publish","type":"wcb_sponsor","link":"https:\/\/sanjose.wordcamp.org\/2017\/sponsor\/ex2outcoding\/","title":{"rendered":"EX2Outcoding"},"content":{"rendered":"<p><a href=\"http:\/\/outcoding.com\/\" target=\"_blank\" rel=\"nofollow\">EX2 Outcoding<\/a> es un proveedor de servicios de tecnolog\u00eda enfocado en brindar soluciones de primer nivel a empresas que buscan servicios rentables y de alta calidad.<\/p>\n<p>Con oficinas ubicadas a 15 minutos del centro de San Jos\u00e9, desde el a\u00f1o 2000 ofrecemos a nuestros clientes experiencia en tecnolog\u00eda y ejecuci\u00f3n de proyectos, asegurando la entrega de una gran variedad de servicios de outsourcing, tales como:<\/p>\n<ul>\n<li>Equipos de Tecnolog\u00eda<\/li>\n<li>Desarrollo de Software<\/li>\n<li>Microsoft Dynamics<\/li>\n<li>Desarrollo de aplicaciones para dispositivos m\u00f3viles<\/li>\n<li>Aseguramiento de calidad y pruebas de software<\/li>\n<li>Dise\u00f1o web<\/li>\n<li>Externalizaci\u00f3n de Procesos de Negocio (BPO)<\/li>\n<\/ul>\n<p>Para m\u00e1s informaci\u00f3n visite: <a href=\"http:\/\/outcoding.com\/\" target=\"_blank\" rel=\"nofollow\">Nearshore Outsourcing<\/a><\/p>\n<hr \/>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/outcoding.com\/\" target=\"_blank\" rel=\"nofollow\">EX\u00b2 Outcoding<\/a> is a premier solution for companies looking for high quality, interactive, and cost-effective software outsourcing. For two decades, we have been providing expertise in technology and project execution to ensure delivery of a broad range of outsourced services such as:<\/p>\n<ul>\n<li>\u00a0Technology Teams Staffing<\/li>\n<li>\u00a0Software Development<\/li>\n<li>\u00a0Microsoft Dynamics<\/li>\n<li>\u00a0Mobile App Development<\/li>\n<li>\u00a0Quality Assurance<\/li>\n<li>\u00a0Web Design<\/li>\n<li>\u00a0Business Process Outsourcing<\/li>\n<li>\u00a0Custom Projects<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>EX2 Outcoding es un proveedor de servicios de tecnolog\u00eda enfocado en brindar soluciones de primer nivel a empresas que buscan servicios rentables y de alta calidad. Con oficinas ubicadas a 15 minutos del centro de San Jos\u00e9, desde el a\u00f1o 2000 ofrecemos a nuestros clientes experiencia en tecnolog\u00eda y ejecuci\u00f3n de proyectos, asegurando la entrega &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/sanjose.wordcamp.org\/2017\/sponsor\/ex2outcoding\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEX2Outcoding\u00bb<\/span><\/a><\/p>\n","protected":false},"featured_media":1129,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"http:\/\/outcoding.com","footnotes":""},"sponsor_level":[4035],"class_list":["post-1013","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-bronze"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-gl","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sponsors\/1013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":7,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sponsors\/1013\/revisions"}],"predecessor-version":[{"id":1133,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sponsors\/1013\/revisions\/1133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media\/1129"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1013"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sponsor_level?post=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}