{"id":770,"date":"2017-06-28T20:42:45","date_gmt":"2017-06-28T20:42:45","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=770"},"modified":"2017-06-28T20:42:45","modified_gmt":"2017-06-28T20:42:45","slug":"jepser-bernardino","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/jepser-bernardino\/","title":{"rendered":"Jepser Bernardino"},"content":{"rendered":"<p>Desarrollador frontend y experto consultor en WordPress de Guatemala. Vive en Barcelona y trabaja con <a href=\"https:\/\/www.typeform.com\" target=\"_blank\">Typeform<\/a>; una startup que revolucion\u00f3 los formularios. Est\u00e1 a cargo de las propiedades p\u00fablicas: el sitio p\u00fablico, help center y blog. Actualmente colabora con el equipo de integraciones, buscando nuevas formas de crecimiento y creando proyectos innovadores.<\/p>\n<p><!--more--><\/p>\n<p>Es creador del plugin WooCredomatic, la integraci\u00f3n de Gravity Forms y Typeform y el plugin oficial de Typeform. Adem\u00e1s desarroll\u00f3 un convertidor de playlist de Spotify a Youtube.<\/p>\n<p>En su charla explicar\u00e1 por qu\u00e9 los detalles importan y compartir\u00e1 su experiencia como developer en Typeform. Actualmente estos proyectos atraen a m\u00e1s de 3 millones de visitas cada mes y siguen creciendo.<\/p>\n<p>Explicar\u00e1 los conceptos detr\u00e1s de las propiedades p\u00fablicas de Typeform, el proceso y por qu\u00e9 \u201craising the bar\u201d es tan importante dentro del equipo de Growth.<\/p>\n<hr>\n<p>Frontend developer and WordPress expert from Guatemala. Living in Barcelona and working at Typeform, a startup that revolutionised forms. He is in charge of the public site, help center, and blog. Currently working with the integration team looking for new ways to grow and creating innovative projects.<\/p>\n<p>He is also creator of the WooCredomatic plugin, an integration of Gravity Forms and Typeform and official WordPress plugin for Typeform.  He also developed a Spotify to Youtube playlist converter.<\/p>\n<p>For his talk, he\u2019ll explain why details matter and share his experience as developer at Typeform. Currently these projects attract more than 3 million users every month and growing.<\/p>\n<p>He will also explain the concepts behind Typeform&#8217;s process and why \u201craising the bar\u201d is so important for our Growth Team.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desarrollador frontend y experto consultor en WordPress de Guatemala. Vive en Barcelona y trabaja con Typeform; una startup que revolucion\u00f3 los formularios. Est\u00e1 a cargo de las propiedades p\u00fablicas: el sitio p\u00fablico, help center y blog. Actualmente colabora con el equipo de integraciones, buscando nuevas formas de crecimiento y creando proyectos innovadores.<\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_wcpt_user_name":"jepser","footnotes":""},"speaker_group":[],"class_list":["post-770","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-cq","jetpack_likes_enabled":true,"avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":1,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/770\/revisions"}],"predecessor-version":[{"id":771,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/770\/revisions\/771"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1301?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speaker_group?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}