{"id":1279,"date":"2017-07-27T03:16:47","date_gmt":"2017-07-27T03:16:47","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1279"},"modified":"2017-07-27T03:58:55","modified_gmt":"2017-07-27T03:58:55","slug":"ifigenia-quintanilla","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ifigenia-quintanilla\/","title":{"rendered":"Ifigenia Quintanilla"},"content":{"rendered":"<p>Desde abril del 2012 p\u00fablica un blog especializado en las esferas de piedra precolombinas y la arqueolog\u00eda del sur de Costa Rica. Es un blog personal, con textos e im\u00e1genes propias que le han permitido tener voz e incidir en la divulgaci\u00f3n, protecci\u00f3n y puesta en valor de este patrimonio mundial.<br \/>\nA su vez un medio de divulgaci\u00f3n cient\u00edfica para todo p\u00fablico donde transmite sus investigaciones.<br \/>\n<!--more--><\/p>\n<p>Escribe para crear conciencia sobre el estado de conservaci\u00f3n de estas esferas y los sitios donde est\u00e1n. Comparte informaci\u00f3n sobre escultura en piedra precolombina de la misma regi\u00f3n e informaci\u00f3n relacionada al mundo ind\u00edgena y precolombino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde abril del 2012 p\u00fablica un blog especializado en las esferas de piedra precolombinas y la arqueolog\u00eda del sur de Costa Rica. Es un blog personal, con textos e im\u00e1genes propias que le han permitido tener voz e incidir en la divulgaci\u00f3n, protecci\u00f3n y puesta en valor de este patrimonio mundial. A su vez un &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ifigenia-quintanilla\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abIfigenia Quintanilla\u00bb<\/span><\/a><\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_wcpt_user_name":"","footnotes":""},"speaker_group":[5771],"class_list":["post-1279","wcb_speaker","type-wcb_speaker","status-publish","hentry","wcb_speaker_group-blogger"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-kD","jetpack_likes_enabled":true,"avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=1279"}],"version-history":[{"count":5,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1279\/revisions"}],"predecessor-version":[{"id":1300,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1279\/revisions\/1300"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1351?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1279"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speaker_group?post=1279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}