{"id":1184,"date":"2017-07-25T18:36:29","date_gmt":"2017-07-25T18:36:29","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1184"},"modified":"2017-07-25T18:36:29","modified_gmt":"2017-07-25T18:36:29","slug":"diego-martinez","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/diego-martinez\/","title":{"rendered":"Diego Mart\u00ednez"},"content":{"rendered":"<p>Diego Mart\u00ednez, funge como estratega digital y es uno de los consultores de Loud Digital, empresa consultora que opera en Costa Rica, M\u00e9xico, Guatemala, El Salvador, Honduras, Panam\u00e1, Venezuela, especializada en SEO, Estrategia Digital y Comercio Electr\u00f3nico, brindando soporte sobre todo a Agencias de Marketing Digital y algunas marcas en esos \u00e1mbitos.<\/p>\n<p><!--more--><\/p>\n<p>Tiene una maestr\u00eda en Marketing Digital con \u00e9nfasis en Ecommerce, de la Universidad de Barcelona, Espa\u00f1a. Sus bases son de comunicaci\u00f3n y mercadeo, adem\u00e1s de una especialidad en producci\u00f3n audiovisual de la Universidad de Buenos Aires, Argentina. <\/p>\n<p>Conferencista Internacional para organizaciones y empresas en M\u00e9xico, Guatemala, El Salvador entre otras, ha trabajado con m\u00faltiples marcas nacionales e internacionales y justamente WordPress ha sido una de las herramientas con las que se apoya para brindar resultados a clientes. <\/p>\n<hr \/>\n<p>Diego Mart\u00ednez, serves as a digital strategist and is one of the consultants of Loud Digital, a consulting firm that operates in Costa Rica, Mexico, Guatemala, El Salvador, Honduras, Panama, Venezuela, specialized in SEO, Digital Strategy and E Commerce. o ignored<\/p>\n<p>They provide support mainly to Digital Marketing Agencies and some brands in those areas. He has a master&#8217;s degree in Digital Marketing with emphasis in Ecommerce (University of Barcelona, Spain).<\/p>\n<p>Its bases are of communication and marketing, besides a specialty in audiovisual production of the University of Buenos Aires, Argentina.<\/p>\n<p>International speaker for organizations and companies in Mexico, Guatemala, El Salvador, among others, he has worked with multiple national and international brands and uses WordPress as one of the tools he relies on to deliver results to clients.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diego Mart\u00ednez, funge como estratega digital y es uno de los consultores de Loud Digital, empresa consultora que opera en Costa Rica, M\u00e9xico, Guatemala, El Salvador, Honduras, Panam\u00e1, Venezuela, especializada en SEO, Estrategia Digital y Comercio Electr\u00f3nico, brindando soporte sobre todo a Agencias de Marketing Digital y algunas marcas en esos \u00e1mbitos.<\/p>\n","protected":false},"author":15118541,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_wcpt_user_name":"","footnotes":""},"speaker_group":[],"class_list":["post-1184","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-j6","jetpack_likes_enabled":true,"avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/15118541"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=1184"}],"version-history":[{"count":2,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1184\/revisions"}],"predecessor-version":[{"id":1202,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1184\/revisions\/1202"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1390?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1184"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speaker_group?post=1184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}