{"id":1147,"date":"2017-07-25T18:44:33","date_gmt":"2017-07-25T18:44:33","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1147"},"modified":"2017-07-25T18:44:54","modified_gmt":"2017-07-25T18:44:54","slug":"lincy-gonzalez-rojas","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/lincy-gonzalez-rojas\/","title":{"rendered":"Lincy Gonz\u00e1lez Rojas"},"content":{"rendered":"<p>Ingeniera en sistemas, con especialidad en desarrollo web y auditor\u00eda.\u00a0 Profesora de la Universidad Nacional desde hace 6 a\u00f1os, actualmente tambi\u00e9n labora para Stateside.<\/p>\n<p><!--more--><\/p>\n<p>Ella ha trabajado para grandes marcas internacionales y a nivel nacional trabaj\u00f3 como parte del equipo de redise\u00f1o en importantes canales de televisi\u00f3n. Actualmente, se encuentra aplicando los principios de miner\u00eda de datos a sus proyectos de inteligencia artificial para mejorar la experiencia del usuario final.<\/p>\n<hr \/>\n<p>Lincy Gonzalez,Software engineer with more than 10 years of experience on web development. On her long career experience she worked on projects for high profile brands. In addition, she worked as part of the redesign team on major television channels .\u00a0<\/p>\n<p>Also she&#8217;s professor at the Costa Rica National University since 2011. Currently she&#8217;s working at StateSides where she&#8217;s developing innovative software applying techniques of data mining and artificial intelligence.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingeniera en sistemas, con especialidad en desarrollo web y auditor\u00eda.\u00a0 Profesora de la Universidad Nacional desde hace 6 a\u00f1os, actualmente tambi\u00e9n labora para Stateside.<\/p>\n","protected":false},"author":15118541,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_wcpt_user_name":"lincgr","footnotes":""},"speaker_group":[],"class_list":["post-1147","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-iv","jetpack_likes_enabled":true,"avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/15118541"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=1147"}],"version-history":[{"count":3,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1147\/revisions"}],"predecessor-version":[{"id":1204,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1147\/revisions\/1204"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1327?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1147"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speaker_group?post=1147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}