{"id":1064,"date":"2017-07-18T03:06:54","date_gmt":"2017-07-18T03:06:54","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1064"},"modified":"2017-07-20T17:12:57","modified_gmt":"2017-07-20T17:12:57","slug":"danny-mora","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/danny-mora\/","title":{"rendered":"Danny Mora"},"content":{"rendered":"<p>Danny Mora, desarrollador web y emprendedor. Ha trabajado en gran cantidad de proyectos personales y para clientes externos, con m\u00e1s de 7 a\u00f1os de experiencia. Licenciado en Desarrollo de Aplicaciones Web y Bachiller universitario en Informatica Educativa. Amante de JavaScript, PHP y Drupal\/WordPress CMS.<br \/>\n<!--more--><br \/>\nHa participado como expositor y colaborador en eventos en Colombia, M\u00e9xico, Guatemala, Panam\u00e1, El Salvador, Nicaragua y sobretodo Costa Rica donde este a\u00f1o participara por segunda vez consecutiva en el Wordcamp, colaborando para el crecimiento esta comunidad y conocer nuevas amistades.<\/p>\n<p>Requisitos deseables:<br \/>\nConocimiento b\u00e1sico de JavaScript.<\/p>\n<hr \/>\n<p>Danny Mora is a senior web developer and entrepreneurship. He has worked on many personal projects and projects for external clients, with more than 7 years of experience. Danny holds a Bachelor&#8217;s degree in Web Application Development and a Bachelor in Informatica Educativa. Lover of JavaScript, PHP and Drupal\/WordPress CMS.<\/p>\n<p>He has participated as an speaker and collaborator in events in Colombia, Mexico, Guatemala, Panama, El Salvador, Nicaragua and Costa Rica where he will participate for the second consecutive year in Wordcamp, collaborating to grow this community and meet new friends.<\/p>\n<p>Preferred Requisites:<br \/>\nBasic JavaScript.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Danny Mora, desarrollador web y emprendedor. Ha trabajado en gran cantidad de proyectos personales y para clientes externos, con m\u00e1s de 7 a\u00f1os de experiencia. Licenciado en Desarrollo de Aplicaciones Web y Bachiller universitario en Informatica Educativa. Amante de JavaScript, PHP y Drupal\/WordPress CMS.<\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_wcpt_user_name":"","footnotes":""},"speaker_group":[],"class_list":["post-1064","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-ha","jetpack_likes_enabled":true,"avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=1064"}],"version-history":[{"count":5,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1064\/revisions"}],"predecessor-version":[{"id":1090,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1064\/revisions\/1090"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1325?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1064"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speaker_group?post=1064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}