{"id":1058,"date":"2017-07-18T02:59:47","date_gmt":"2017-07-18T02:59:47","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1058"},"modified":"2017-07-27T00:36:12","modified_gmt":"2017-07-27T00:36:12","slug":"rommel-castro","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/rommel-castro\/","title":{"rendered":"Rommel Castro"},"content":{"rendered":"<p>Web Engineer 9 a\u00f1os desarrollando, 2 a\u00f1os contribuyendo a Ha estado enamorado de WordPress desde la versi\u00f3n 2.7. Comenz\u00f3 el grupo local de WordPress en Costa Rica y tambi\u00e9n es activo en los foros de ayuda.<\/p>\n<p><!--more--><\/p>\n<p>Web Engineer 9 years as dev 2 as contributor. He\u2019s been in love with WordPress since version 2.7, he loves building solutions based on WordPress. He started a local WordPress group in Costa Rica and it\u2019s also active on forums helping people with their issues.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Web Engineer 9 a\u00f1os desarrollando, 2 a\u00f1os contribuyendo a Ha estado enamorado de WordPress desde la versi\u00f3n 2.7. Comenz\u00f3 el grupo local de WordPress en Costa Rica y tambi\u00e9n es activo en los foros de ayuda.<\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_wcpt_user_name":"rommelxcastro","footnotes":""},"speaker_group":[],"class_list":["post-1058","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-h4","jetpack_likes_enabled":true,"avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=1058"}],"version-history":[{"count":4,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1058\/revisions"}],"predecessor-version":[{"id":1253,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1058\/revisions\/1253"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1293?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speaker_group?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}