{"id":1490,"date":"2017-07-27T17:42:32","date_gmt":"2017-07-27T17:42:32","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_session&#038;p=1490"},"modified":"2017-07-27T17:42:32","modified_gmt":"2017-07-27T17:42:32","slug":"accesibilidad-en-la-web-y-wordpress","status":"publish","type":"wcb_session","link":"https:\/\/sanjose.wordcamp.org\/2017\/session\/accesibilidad-en-la-web-y-wordpress\/","title":{"rendered":"Accesibilidad en la Web y WordPress"},"content":{"rendered":"<p>Exploraremos como una persona con discapacidad visual interacciona con una web regular no accesible \/ accesible. Lo que nos dara un enfoque de que deberiamso tener en nuestro sitio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exploraremos como una persona con discapacidad visual interacciona con una web regular no accesible \/ accesible. Lo que nos dara un enfoque de que deberiamso tener en nuestro sitio.<\/p>\n","protected":false},"author":319559,"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_session_time":1504439100,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[1488],"footnotes":""},"session_track":[35679],"session_category":[],"class_list":["post-1490","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-escalante"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-o2","jetpack_likes_enabled":true,"session_date_time":{"date":"septiembre 3, 2017","time":"11:45 am"},"session_speakers":[{"id":"1488","slug":"leonardo-segura-penaranda","name":"Leonardo Segura Pe\u00f1aranda","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/leonardo-segura-penaranda\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/319559"}],"version-history":[{"count":1,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1490\/revisions"}],"predecessor-version":[{"id":1491,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1490\/revisions\/1491"}],"speakers":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1488"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1490"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_track?post=1490"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_category?post=1490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}