{"id":1329,"date":"2017-07-27T04:34:10","date_gmt":"2017-07-27T04:34:10","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_session&#038;p=1329"},"modified":"2017-09-30T16:09:24","modified_gmt":"2017-09-30T16:09:24","slug":"accesibilidad-desde-las-primeras-etapas-del-ux","status":"publish","type":"wcb_session","link":"https:\/\/sanjose.wordcamp.org\/2017\/session\/accesibilidad-desde-las-primeras-etapas-del-ux\/","title":{"rendered":"Accesibilidad desde las primeras etapas del UX"},"content":{"rendered":"<p>Tomar en cuenta a todas las personas incluyendo persona con discapacidades sensoriales, f\u00edsicas y visuales por medio de buenas pr\u00e1cticas en el dise\u00f1o de la experiencia del usuario desde tempranos momentos del proceso de dise\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tomar en cuenta a todas las personas incluyendo persona con discapacidades sensoriales, f\u00edsicas y visuales por medio de buenas pr\u00e1cticas en el dise\u00f1o de la experiencia del usuario desde tempranos momentos del proceso de dise\u00f1o.<\/p>\n","protected":false},"author":319559,"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_session_time":1504447800,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"https:\/\/drive.google.com\/file\/d\/0B7mE8KxvoA4JUDNxdFl2amtmMjg\/view?usp=sharing","_wcpt_session_video":"","_wcpt_speaker_id":[1156],"footnotes":""},"session_track":[35679],"session_category":[],"class_list":["post-1329","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-escalante"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-lr","jetpack_likes_enabled":true,"session_date_time":{"date":"septiembre 3, 2017","time":"2:10 pm"},"session_speakers":[{"id":"1156","slug":"carlos-murillo","name":"Carlos Murillo","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/carlos-murillo\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/319559"}],"version-history":[{"count":1,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1329\/revisions"}],"predecessor-version":[{"id":1364,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1329\/revisions\/1364"}],"speakers":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1156"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1329"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_track?post=1329"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_category?post=1329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}