{"id":1324,"date":"2017-07-27T04:07:50","date_gmt":"2017-07-27T04:07:50","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/?post_type=wcb_session&#038;p=1324"},"modified":"2017-08-01T15:27:25","modified_gmt":"2017-08-01T15:27:25","slug":"cross-platform-react","status":"publish","type":"wcb_session","link":"https:\/\/sanjose.wordcamp.org\/2017\/session\/cross-platform-react\/","title":{"rendered":"Cross Platform React"},"content":{"rendered":"<p>Como crear una arquitectura para reactDom \/ ReactNative que permita compartir logica entre aplicaciones(iOS, android, web) usando Redux y dump components, tambien veremos como usar el mismo api de localstorage en ReactNative(async storage) y reactDOM(localstorage). Permitiendo reciclar hasta el 80% del codigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como crear una arquitectura para reactDom \/ ReactNative que permita compartir logica entre aplicaciones(iOS, android, web) usando Redux y dump components, tambien veremos como usar el mismo api de localstorage en ReactNative(async storage) y reactDOM(localstorage). Permitiendo reciclar hasta el 80% del codigo.<\/p>\n","protected":false},"author":319559,"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_session_time":1504445100,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[1224],"footnotes":""},"session_track":[35678],"session_category":[],"class_list":["post-1324","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-la-cali"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheNhY-lm","jetpack_likes_enabled":true,"session_date_time":{"date":"septiembre 3, 2017","time":"1:25 pm"},"session_speakers":[{"id":"1224","slug":"abdel-atencio-valenciano","name":"Abdel Atencio Valenciano","link":"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/abdel-atencio-valenciano\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/319559"}],"version-history":[{"count":1,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1324\/revisions"}],"predecessor-version":[{"id":1354,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/sessions\/1324\/revisions\/1354"}],"speakers":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/speakers\/1224"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1324"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_track?post=1324"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/session_category?post=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}