{"id":8,"date":"2017-03-31T08:50:58","date_gmt":"2017-03-31T08:50:58","guid":{"rendered":"https:\/\/2017.sanjose.wordcamp.org\/speakers\/"},"modified":"2017-06-28T20:46:11","modified_gmt":"2017-06-28T20:46:11","slug":"speakers","status":"publish","type":"page","link":"https:\/\/sanjose.wordcamp.org\/2017\/speakers\/","title":{"rendered":"Speakers"},"content":{"rendered":"\n\t<div class=\"wcorg-speakers\">\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-carlos-roberto-fonseca\" class=\"wcorg-speaker wcorg-speaker-carlos-roberto-fonseca wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tCarlos Roberto Fonseca\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/53a2f52ba760459a20678976fe64424ec82a966bba6522b33b349a0a8e0bc0f7?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/53a2f52ba760459a20678976fe64424ec82a966bba6522b33b349a0a8e0bc0f7?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Consultor de medios digitales y marketing digital. M\u00e1ster en Tecnolog\u00eda de la Informaci\u00f3n (Arquitectura de la Informaci\u00f3n) en la Universidad de Aalborg en Dinamarca. Fellowship en Periodismo Digital en la International Academy of Journalism en Alemania y Licenciatura en Comunicaci\u00f3n Social en la Universidad Centroamericana en Nicaragua.  <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/carlos-roberto-fonseca\/#more-1138\" class=\"more-link\"><span aria-label=\"Sigue leyendo Carlos Roberto Fonseca\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-jepser-bernardino\" class=\"wcorg-speaker wcorg-speaker-jepser-bernardino wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJepser Bernardino\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5e556e7e5bb44ccbf0f19ed2a4aa5e4a583391e4a603792440fa5493e2dc9448?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Desarrollador frontend y experto consultor en WordPress de Guatemala. Vive en Barcelona y trabaja con <a href=\"https:\/\/www.typeform.com\" target=\"_blank\">Typeform<\/a>; una startup que revolucion\u00f3 los formularios. Est\u00e1 a cargo de las propiedades p\u00fablicas: el sitio p\u00fablico, help center y blog. Actualmente colabora con el equipo de integraciones, buscando nuevas formas de crecimiento y creando proyectos innovadores.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/jepser-bernardino\/#more-770\" class=\"more-link\"><span aria-label=\"Sigue leyendo Jepser Bernardino\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-carlos-cordero\" class=\"wcorg-speaker wcorg-speaker-carlos-cordero wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tCarlos Cordero\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/1b67b35125388507b5802e3498fb379a440943e37b3dd0947266dd86819ea8f5?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/1b67b35125388507b5802e3498fb379a440943e37b3dd0947266dd86819ea8f5?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Periodista de El Financiero donde realiza cobertura de temas de tecnolog\u00eda y coordina \/ edita publicaciones de la secci\u00f3n de pymes. Editor de revistas de tecnolog\u00eda y telecomunicaciones, y Premio de Periodismo en Ciencia y Tecnolog\u00eda 2003-2004.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/carlos-cordero\/#more-1236\" class=\"more-link\"><span aria-label=\"Sigue leyendo Carlos Cordero\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-vekoh-pardo\" class=\"wcorg-speaker wcorg-speaker-vekoh-pardo wcorg-track-amon wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tVekoh Pardo\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/1e01027282b5a603bbf85f3704c37e9cde2bc7ac6975ab195e1dd40bc1b5b5b1?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/1e01027282b5a603bbf85f3704c37e9cde2bc7ac6975ab195e1dd40bc1b5b5b1?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Vekoh Pardo es Ingeniero Industrial, empresario y desde hace m\u00e1s de 17 a\u00f1os trabaja como Gerente General de Admintek S.A., su pasi\u00f3n es asesorar a sus clientes en cuanto al uso de plataformas web lo que lo llevo a implementar m\u00e9todos efectivos y seguros para los WordPress de sus clientes.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/vekoh-pardo\/#more-2293\" class=\"more-link\"><span aria-label=\"Sigue leyendo Vekoh Pardo\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-paula-acuna\" class=\"wcorg-speaker wcorg-speaker-paula-acuna wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tPaula Acu\u00f1a\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/61e1035df20aae851400c35f18ebcd4923081ab588687566fe7838a085ae048f?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/61e1035df20aae851400c35f18ebcd4923081ab588687566fe7838a085ae048f?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Paula Acu\u00f1a es M\u00e1ster en Administraci\u00f3n de Empresas con \u00c9nfasis en Mercadeo, Arquitecta y Coach , lo que deja en evidencia su leve d\u00e9ficit atencional. Especialista en Marketing online, lectora obsesiva, escritora del blog Soy Empresario ECO y profesora universitaria. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/paula-acuna\/#more-1134\" class=\"more-link\"><span aria-label=\"Sigue leyendo Paula Acu\u00f1a\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-damian-suarez\" class=\"wcorg-speaker wcorg-speaker-damian-suarez wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tDami\u00e1n Su\u00e1rez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/9ff3405a86b8178158b444dc6b44fc3ef321c9641b6d95a769956e7b50c26909?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/9ff3405a86b8178158b444dc6b44fc3ef321c9641b6d95a769956e7b50c26909?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Bajo el pseud\u00f3nimo de retrofox, es programador y desarrollador web. Code Wrangler en Automattic comprometido principalmente en los proyectos de Calipso y la librer\u00eda wpcom.js.<br \/>\nAmante de javascript y los eventos desarticulados,  juega al f\u00fatbol, murguista (tipo uruguayo), carpintero, herrero y alba\u00f1il de su propia casa, y un sin fin de etc\u00e9teras.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/damian-suarez\/#more-778\" class=\"more-link\"><span aria-label=\"Sigue leyendo Dami\u00e1n Su\u00e1rez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-leonardo-segura-penaranda\" class=\"wcorg-speaker wcorg-speaker-leonardo-segura-penaranda wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tLeonardo Segura Pe\u00f1aranda\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/28c6b6e5ee04c0e7dc326cd85ecc52d5b3e273df6b10cd04272c33909f1a956f?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/28c6b6e5ee04c0e7dc326cd85ecc52d5b3e273df6b10cd04272c33909f1a956f?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Leonardo tiene amplia experiencia en dise\u00f1o de materiales y t\u00e9cnicas para la capacitaci\u00f3n de adultos.<br \/>\nHe desarrollado capacitaciones y ponencias sobre personas con discapacidad, accesibilidad, derechos humanos, accesibilidad y nuevas tecnolog\u00edas.<br \/>\nHa brindado servicios de consultor\u00eda en comunicaci\u00f3n y relaciones p\u00fablicas orientados a la elaboraci\u00f3n de productos de comunicaci\u00f3n y la organizaci\u00f3n de actividades especiales.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-elio-rivero\" class=\"wcorg-speaker wcorg-speaker-elio-rivero wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tElio Rivero\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ebb0432bd024e3f7688fbee07fc0bde415382809640e507331badb733d61871c?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ebb0432bd024e3f7688fbee07fc0bde415382809640e507331badb733d61871c?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Elio es programador, dise\u00f1ador y contribuidor al core de WordPress. Trabaja como Code Wrangler en Automattic en el plugin Jetpack para WordPress, principalmente en la interface de Jetpack construida con React y Redux y que emplea la REST API; y en Calypso, la interface JavaScript de WordPress.com.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/elio-rivero\/#more-764\" class=\"more-link\"><span aria-label=\"Sigue leyendo Elio Rivero\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-allan-andres-chaves\" class=\"wcorg-speaker wcorg-speaker-allan-andres-chaves wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tAllan Andr\u00e9s Chaves\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/cd9876e03e90bbfa9e06f546d259ce728f31002fede4c08385af655ae16e6a0e?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/cd9876e03e90bbfa9e06f546d259ce728f31002fede4c08385af655ae16e6a0e?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Allan es un emprendedor polifac\u00e9tico, oriundo de San Carlos, su experiencia con WordPress inicia hace 3 a\u00f1os, trabajando blogs tematicos y luego paginas completas para clientes. Promotor de Eventos, Consultor\u00edas, Comunity Manager, Social Media, MK, actividades culturales, noticias, entretenimiento y m\u00e1s.  <\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-jose-gutierrez\" class=\"wcorg-speaker wcorg-speaker-jose-gutierrez wcorg-track-amon wcorg-track-escalante wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJos\u00e9 Guti\u00e9rrez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/87d10d5bbbe6e90edc921c4b46c00297c285b2b52399598f8cfde224c44bba98?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/87d10d5bbbe6e90edc921c4b46c00297c285b2b52399598f8cfde224c44bba98?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Jos\u00e9 Guti\u00e9rrez dise\u00f1a soluciones junto con clientes y usuarios. Con sus estudios en Comunicaci\u00f3n de la Universidad de Costa Rica, se involucra en la estrategia digital de las organizaciones que trabaja, creando soluciones que permean no s\u00f3lo la interfaz, sino la organizaci\u00f3n y c\u00f3mo \u00e9sta se comunica en cada interacci\u00f3n con sus usuarios.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/jose-gutierrez\/#more-2204\" class=\"more-link\"><span aria-label=\"Sigue leyendo Jos\u00e9 Guti\u00e9rrez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-arturo-quiros-lepiz\" class=\"wcorg-speaker wcorg-speaker-arturo-quiros-lepiz wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tArturo Quir\u00f3s L\u00e9piz\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/2d84aaa891b0cf532f8c95bfaa302a09869c7667ac9d576562024bf57c8f5884?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/2d84aaa891b0cf532f8c95bfaa302a09869c7667ac9d576562024bf57c8f5884?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Arturo es ingeniero en sistemas con 20 a\u00f1os de experiencia en desarrollo de software, innovaci\u00f3n, marketing digital y neurociencias. Habiendo trabajado desde los 13 a\u00f1os conoce y comprende el valor del trabajo duro y la recompensa de la superaci\u00f3n y el reinventarse constantemente.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/arturo-quiros-lepiz\/#more-1102\" class=\"more-link\"><span aria-label=\"Sigue leyendo Arturo Quir\u00f3s L\u00e9piz\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-gabo-esquivel\" class=\"wcorg-speaker wcorg-speaker-gabo-esquivel wcorg-track-amon wcorg-track-escalante wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tGabo Esquivel\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/01edf0d18c21c3e184525251ee30a289cf9f18ef8b86d5ede6e908b3856b779e?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/01edf0d18c21c3e184525251ee30a289cf9f18ef8b86d5ede6e908b3856b779e?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Cloud, DevOps, Lean and Open Source technology, particularly JavaScript. Software engineering and staff augmentation services through corticaltouch.com<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-julian-alvarado\" class=\"wcorg-speaker wcorg-speaker-julian-alvarado wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJuli\u00e1n Alvarado\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/a3b52bc37f3b43727ab83ff2af9f7d4c230ad05d6ce56ed5c60ea5cb9ae4c6c2?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/a3b52bc37f3b43727ab83ff2af9f7d4c230ad05d6ce56ed5c60ea5cb9ae4c6c2?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Julian Alvarado es un emprendedor con experiencia en UX y desarrollo front end. Su experiencia con WordPress inici\u00f3 en el 2010 con el inicio de su estudio de outsourcing y posterior a eso trabajando con Woocommerce como la mejor soluci\u00f3n de eCommerce en el mercado latino.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/julian-alvarado\/#more-1229\" class=\"more-link\"><span aria-label=\"Sigue leyendo Juli\u00e1n Alvarado\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-cristian-sanchez\" class=\"wcorg-speaker wcorg-speaker-cristian-sanchez wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tCristian S\u00e1nchez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/866ace510faee18fae439fc3f2bc9a7f098260ea7902a4a7f2dd97d12ff3effc?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/866ace510faee18fae439fc3f2bc9a7f098260ea7902a4a7f2dd97d12ff3effc?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Cristian es CEO de Ricenbeans, empresa enfocada al marketing digital y el desarrollo de sitios web sobre WordPress. Tiene 27 a\u00f1os, de los cuales 9 ha trabajado desarrollando sitios web en WordPress, desde su versi\u00f3n individual, hasta multisitios.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/cristian-sanchez\/#more-918\" class=\"more-link\"><span aria-label=\"Sigue leyendo Cristian S\u00e1nchez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-irene-issa-el-khoury\" class=\"wcorg-speaker wcorg-speaker-irene-issa-el-khoury wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tIrene Issa El Khoury\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ddf7dcb5b5930b76c779ab8089a51fa79f4604b6fde1422aaa1dd88a01926eee?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ddf7dcb5b5930b76c779ab8089a51fa79f4604b6fde1422aaa1dd88a01926eee?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Es Ingeniera en Disen\u0303o Industrial y cuenta una maestri\u0301a en Comunicacio\u0301n y Mercadeo. Adem\u00e1s, cuenta con una especializacio\u0301n en Design Thinking de The School of Design Thinking del Hasso Platner Institut en Berli\u0301n, Alemania. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/irene-issa-el-khoury\/#more-1163\" class=\"more-link\"><span aria-label=\"Sigue leyendo Irene Issa El Khoury\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-ana-laura-mora\" class=\"wcorg-speaker wcorg-speaker-ana-laura-mora wcorg-track-amon wcorg-track-escalante wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tAna Laura Mora\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/1b3783736c5fa452e914a18a6ea7cd633d7dc37500da3f8302fc6609623f78b5?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/1b3783736c5fa452e914a18a6ea7cd633d7dc37500da3f8302fc6609623f78b5?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Ana es una apasionada creadora de contenido, que cree en el poder de contar historias y los individuos en la tecnolog\u00eda. Estudi\u00f3 publicidad hace un tiempo y ha trabajado desde entonces para construir una comunidad que da poder a las personas que aman crear y comunicarse.  <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ana-laura-mora\/#more-1269\" class=\"more-link\"><span aria-label=\"Sigue leyendo Ana Laura Mora\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-carl-alexander\" class=\"wcorg-speaker wcorg-speaker-carl-alexander wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tCarl Alexander\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/9dc50dba9cc5e4bf097f44026034daa66e2ed552549ba363304ff22914f4c0d1?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/9dc50dba9cc5e4bf097f44026034daa66e2ed552549ba363304ff22914f4c0d1?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Carl Alexander es programador PHP de Montr\u00e9al en Canad\u00e1. Tiene un <a href=\"https:\/\/carlalexander.ca\/\">sitio web<\/a> donde publica art\u00edculos regularmente. Es su manera de ayudar la comunidad WordPress a aprender esos conceptos complejos. Es tambi\u00e9n porque est\u00e1 alegre de dar una charla por WordCamp San Jos\u00e9. Es otra manera para el de ayudar.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/carl-alexander\/#more-916\" class=\"more-link\"><span aria-label=\"Sigue leyendo Carl Alexander\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-ifigenia-quintanilla\" class=\"wcorg-speaker wcorg-speaker-ifigenia-quintanilla wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tIfigenia Quintanilla\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ce232ef9d42330b8388f1836fba6d46915b6a560a8b6514ba3d6b280a4a7f30d?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Desde abril del 2012 p\u00fablica un blog especializado en las esferas de piedra precolombinas y la arqueolog\u00eda del sur de Costa Rica. Es un blog personal, con textos e im\u00e1genes propias que le han permitido tener voz e incidir en la divulgaci\u00f3n, protecci\u00f3n y puesta en valor de este patrimonio mundial.<br \/>\nA su vez un medio de divulgaci\u00f3n cient\u00edfica para todo p\u00fablico donde transmite sus investigaciones.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ifigenia-quintanilla\/#more-1279\" class=\"more-link\"><span aria-label=\"Sigue leyendo Ifigenia Quintanilla\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-johanna-alfaro\" class=\"wcorg-speaker wcorg-speaker-johanna-alfaro wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJohanna Alfaro\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/7769d7fa82a6d7181c3d3746e64f206ed35ef0561dd681b00a92e5eb431d3e42?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/7769d7fa82a6d7181c3d3746e64f206ed35ef0561dd681b00a92e5eb431d3e42?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Headhunter de profesi\u00f3n y autoproclamada gaticornio. Johanna nos trae m\u00e1s de 10 a\u00f1os de experiencia creando estrategias de branding efectivo, energ\u00eda positiva y habilidades de networker. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/johanna-alfaro\/#more-1116\" class=\"more-link\"><span aria-label=\"Sigue leyendo Johanna Alfaro\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-jose-neira\" class=\"wcorg-speaker wcorg-speaker-jose-neira wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJos\u00e9 Neira\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/eb0759883dd7e3cfe42fab98b8f2438e60c2658d1fec8b78d94983ebb22a25ca?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/eb0759883dd7e3cfe42fab98b8f2438e60c2658d1fec8b78d94983ebb22a25ca?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Es Ingeniero en Inform\u00e1tica, empresario, desarrollador web y consultor de Marketing online con \u00e9nfasis en SEO y WordPress. Tiene un Podcast en http:\/\/BlogDeMarketingOnline.com y cada semana comparte consejos de Marketing Online, Neuromarketing y por supuesto dise\u00f1o web con WordPress.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/jose-neira\/#more-1056\" class=\"more-link\"><span aria-label=\"Sigue leyendo Jos\u00e9 Neira\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-luis-angel-rodriguez\" class=\"wcorg-speaker wcorg-speaker-luis-angel-rodriguez\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tLuis \u00c1ngel Rodr\u00edguez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/bb986b9b381bc78253402a20a4daf1ae99334c6378473e6c298dbaf2f533d6e0?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/bb986b9b381bc78253402a20a4daf1ae99334c6378473e6c298dbaf2f533d6e0?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p><span id=\"result_box\" class=\"\" lang=\"es\">Luis tiene m\u00e1s de 13 a\u00f1os de experiencia trabajando en Desarrollo Web. <span class=\"\">Ha desempe\u00f1ado un papel crucial en la agencia Hangar (www.thehangar.cr), desarrollando el equipo de back-end y garantizando la m\u00e1s alta calidad para el trabajo realizado para sus clientes.<\/span><\/span><\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/luis-angel-rodriguez\/#more-1721\" class=\"more-link\"><span aria-label=\"Sigue leyendo Luis \u00c1ngel Rodr\u00edguez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-carlos-murillo\" class=\"wcorg-speaker wcorg-speaker-carlos-murillo wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tCarlos Murillo\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/841fd0f092ac3dd3545b063c0651709637c62494af537a8c1c03c518b8c7c6af?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/841fd0f092ac3dd3545b063c0651709637c62494af537a8c1c03c518b8c7c6af?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Carlos Murillo es un innovador dise\u00f1ador de experiencia de usuario con m\u00e1s de 10 a\u00f1os de experiencia en dise\u00f1o centrado en el usuario y usabilidad. <\/p>\n<p>Ense\u00f1a Usabilidad Web como parte del Programa de Dise\u00f1o Web en FUNDATEC, ITCR. Defensor de la accesibilidad.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/carlos-murillo\/#more-1156\" class=\"more-link\"><span aria-label=\"Sigue leyendo Carlos Murillo\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-aura-lila-gutierrez-tejada\" class=\"wcorg-speaker wcorg-speaker-aura-lila-gutierrez-tejada wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tAura Lila Guti\u00e9rrez Tejada\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/11ed205713ce9a464cba800853daba0319eb70c49241bc8cc18105dc4238e34f?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/11ed205713ce9a464cba800853daba0319eb70c49241bc8cc18105dc4238e34f?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>5 a\u00f1os desarrollando en WordPress, miembro de la comunidad WordPress Nicaragua y 3 veces co-organizadora del WordCamp Managua .<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-rommel-castro\" class=\"wcorg-speaker wcorg-speaker-rommel-castro wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tRommel Castro\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/1c3efba3ed44470b70e95115583e3db5f4208f65f0519176fd52dd46a75d6a89?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Web Engineer 9 a\u00f1os desarrollando, 2 a\u00f1os contribuyendo a Ha estado enamorado de WordPress desde la versi\u00f3n 2.7. Comenz\u00f3 el grupo local de WordPress en Costa Rica y tambi\u00e9n es activo en los foros de ayuda.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/rommel-castro\/#more-1058\" class=\"more-link\"><span aria-label=\"Sigue leyendo Rommel Castro\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-francisco-calderon\" class=\"wcorg-speaker wcorg-speaker-francisco-calderon wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tFrancisco Calder\u00f3n\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/9e2cda1a25d8af99683872304ee03b706a7d2aafd0e4f96d560920e99134d5de?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/9e2cda1a25d8af99683872304ee03b706a7d2aafd0e4f96d560920e99134d5de?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Desarrollador Full Stack, emprendedor y educador. Co-fundador de la comunidad de WordPress Guatemala, con 9 a\u00f1os de experiencia en Desarrollo Web y 7 a\u00f1os utilizando WordPress.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/francisco-calderon\/#more-1054\" class=\"more-link\"><span aria-label=\"Sigue leyendo Francisco Calder\u00f3n\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-brian-salazar\" class=\"wcorg-speaker wcorg-speaker-brian-salazar wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tBrian Salazar\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/bdf9e416b2b4afa708c3d6b94b3769e1df80cf624d085099d6c9233e0cdf2729?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/bdf9e416b2b4afa708c3d6b94b3769e1df80cf624d085099d6c9233e0cdf2729?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Es un consultor digital enfocado al desarrollo de soluciones digitales no convencionales, desarroll\u00f3 una metodolog\u00eda de ense\u00f1anza que pone en pr\u00e1ctica en la academia digital La 404. Junto a la aventura de docencia, co-fund\u00f3 una empresa enfocada en la extracci\u00f3n y miner\u00eda de datos para la utilizaci\u00f3n en \u00e1reas como publicidad, mercadeo e investigaci\u00f3n llamada Minerva. Adem\u00e1s trabaja como consultor en BrainLayer, una de las primeras empresas especializadas en marketing de inteligencia.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/brian-salazar\/#more-1145\" class=\"more-link\"><span aria-label=\"Sigue leyendo Brian Salazar\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-karen-amador-jimenez\" class=\"wcorg-speaker wcorg-speaker-karen-amador-jimenez wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tKaren Amador Jim\u00e9nez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/a5137aca47137a47d0a1cc630bee846740148008fef9b03f3d18bb12a09d5724?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/a5137aca47137a47d0a1cc630bee846740148008fef9b03f3d18bb12a09d5724?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Karen es Psic\u00f3loga Cl\u00ednica, Master en Psicolog\u00eda Industrial &amp; Organizacional con experiencia en Psicoterapia, Docencia y Gesti\u00f3n del Talento Humano. Propietaria y Bloguera del Sitio Web realizado en WordPress www.ticamoderna.com con el cual ha aprendido de WordPress y le ha encantado. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/karen-amador-jimenez\/#more-1136\" class=\"more-link\"><span aria-label=\"Sigue leyendo Karen Amador Jim\u00e9nez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-catalina-brenes\" class=\"wcorg-speaker wcorg-speaker-catalina-brenes wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tCatalina Brenes\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/986c4ec6ac4f6bd14fd03d68d458050c8dfc7be616a2e5a219216c177267dc23?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/986c4ec6ac4f6bd14fd03d68d458050c8dfc7be616a2e5a219216c177267dc23?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Es cal\u00edgrafa creativa y dise\u00f1adora. Se ha centrado en mostrar la magia de la caligraf\u00eda y dise\u00f1o de letras a otros. ElTintero es su marca donde ense\u00f1a a docenas de personas mensualmente c\u00f3mo crear hermosas cartas desde cero. <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/catalina-brenes\/#more-1288\" class=\"more-link\"><span aria-label=\"Sigue leyendo Catalina Brenes\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-danny-mora\" class=\"wcorg-speaker wcorg-speaker-danny-mora wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tDanny Mora\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/6453b2444bf8e401ba3129cb2a6f9d6180208905b406451fed61474f99042050?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Danny Mora, desarrollador web y emprendedor. Ha trabajado en gran cantidad de proyectos personales y para clientes externos, con m\u00e1s de 7 a\u00f1os de experiencia. Licenciado en Desarrollo de Aplicaciones Web y Bachiller universitario en Informatica Educativa. Amante de JavaScript, PHP y Drupal\/WordPress CMS.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/danny-mora\/#more-1064\" class=\"more-link\"><span aria-label=\"Sigue leyendo Danny Mora\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-leonel-lopez\" class=\"wcorg-speaker wcorg-speaker-leonel-lopez wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tLeonel L\u00f3pez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/9bd97240e878781db571a87d047fe5e4e0ebe2b681059fef037d4c703e3a3ff5?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/9bd97240e878781db571a87d047fe5e4e0ebe2b681059fef037d4c703e3a3ff5?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Es una persona sorda y es programador web con 10 a\u00f1os de experiencia desarrollando proyectos web en las diferentes empresas a nivel internacional como nacional tales como SITEL, EBOS, Logosoft, Sweneno, Multipagos Costa Rica, entre muchas otras.  Se desempe\u00f1a como freelancer.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/leonel-lopez\/#more-1210\" class=\"more-link\"><span aria-label=\"Sigue leyendo Leonel L\u00f3pez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-diego-martinez\" class=\"wcorg-speaker wcorg-speaker-diego-martinez wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tDiego Mart\u00ednez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4fd9830db0ece1f0f2e72f18b1bdde1d1878cdde15effa9b5e054176f6b94b50?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Diego Mart\u00ednez, funge como estratega digital y es uno de los consultores de Loud Digital, empresa consultora que opera en Costa Rica, M\u00e9xico, Guatemala, El Salvador, Honduras, Panam\u00e1, Venezuela, especializada en SEO, Estrategia Digital y Comercio Electr\u00f3nico, brindando soporte sobre todo a Agencias de Marketing Digital y algunas marcas en esos \u00e1mbitos.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/diego-martinez\/#more-1184\" class=\"more-link\"><span aria-label=\"Sigue leyendo Diego Mart\u00ednez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-luis-matarrita\" class=\"wcorg-speaker wcorg-speaker-luis-matarrita wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tLuis Matarrita\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/0d44b3cc88efb9b1c645b8b0fd33e9c5b8507bdacb4366c454e2fec110420e46?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/0d44b3cc88efb9b1c645b8b0fd33e9c5b8507bdacb4366c454e2fec110420e46?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Ingeniero graduado en grado y postgrado de la UCR. Inici\u00f3 con WordPress en el 2009 y actualmente trabaja como consultor independiente haciendo desarrollo de sitios personalizados  basados en WordPress en proyectos a nivel nacional e internacional en las \u00e1reas de comunicaci\u00f3n colectiva, comercio electr\u00f3nico, sitios corporativos y aplicaciones especializadas. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/luis-matarrita\/#more-1140\" class=\"more-link\"><span aria-label=\"Sigue leyendo Luis Matarrita\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-ernesto-morales\" class=\"wcorg-speaker wcorg-speaker-ernesto-morales wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tErnesto Morales\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/876e091e6ec218e09c413a055ef7f3c566c44104d6334daec85af602ad686066?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/876e091e6ec218e09c413a055ef7f3c566c44104d6334daec85af602ad686066?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Posee m\u00e1s de 20 a\u00f1os de experiencia en la creaci\u00f3n de portales y sitios web, empleando diversos lenguajes de programaci\u00f3n.  Lo que lo llev\u00f3 a trabajar con WordPress durante los \u00faltimos 10 a\u00f1os.  Dada la versatilidad, seguridad y facilidad de uso, se inclin\u00f3 por favorecer el uso de esta herramienta para todos los proyectos web.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ernesto-morales\/#more-1195\" class=\"more-link\"><span aria-label=\"Sigue leyendo Ernesto Morales\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-zac-gordon\" class=\"wcorg-speaker wcorg-speaker-zac-gordon wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tZac Gordon\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/7935c73cce64694600738d5ed4a6e464d2ba445af9a7ba375708a815dc90b585?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/7935c73cce64694600738d5ed4a6e464d2ba445af9a7ba375708a815dc90b585?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Zac es un experimentado educador, que ha estado ense\u00f1ando y construyendo APPS con WordPress desde el 2005, dedicado a la ense\u00f1anza, formando estudiantes y profesionales con solidas bases en los fundamentos, las mejores pr\u00e1cticas y las \u00faltimas tendencias en la web. En este momento, est\u00e1 especialmente centrado en el desarrollo de WordPress, el API y JavaScript.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/zac-gordon\/#more-766\" class=\"more-link\"><span aria-label=\"Sigue leyendo Zac Gordon\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-yuls-walters\" class=\"wcorg-speaker wcorg-speaker-yuls-walters wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tYuls Walters\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/7f42a8d756335c7c6e8036f00d4016b11bbb6a70a12aaad0d0fb72eb323da12d?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/7f42a8d756335c7c6e8036f00d4016b11bbb6a70a12aaad0d0fb72eb323da12d?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Unicornio disfrazado de dise\u00f1adora, ingeniera en dise\u00f1o industrial y aficionada a la jardiner\u00eda. Se especializa en usabilidad y dise\u00f1o centrado en el usuario. Emprendedora, l\u00edder del equipo de dise\u00f1o y socia en Huli, uno de los primeros startups en Costa Rica y el mejor a nivel mundial en el campo de la salud digital, seg\u00fan Google Exchange for Entrepreneurs 2016.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/yuls-walters\/#more-1068\" class=\"more-link\"><span aria-label=\"Sigue leyendo Yuls Walters\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-christie-chirinos\" class=\"wcorg-speaker wcorg-speaker-christie-chirinos wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tChristie Chirinos\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/8301596d03ec4066862757057e54e2a7bf6bc601a15075bb970eba52f5bbebe3?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/8301596d03ec4066862757057e54e2a7bf6bc601a15075bb970eba52f5bbebe3?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Christie Chirinos es socia y directora de desarrollo del negocios en Caldera Labs, creadores de Caldera Forms. Christie creo su primer sitio web a los 14 a\u00f1os, el cual ten\u00eda un formulario de contacto para posibles clientes a su negocio de clases de piano. Tambi\u00e9n a creado sirios web en WordPress para negocios, un blog, y a trabajando de directora de comunicaciones web para dos organizaciones sin fines de lucro en Nueva York, antes de llegar a Caldera Labs. Christie recibi\u00f3 su maestr\u00eda de administraci\u00f3n de empresas en la Universidad Estatal de Florida (Florida State University), y actualmente vive en Nueva York &#8211; tristemente lejos de su familia en Lima, Per\u00fa.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-auxiliadora-martinez\" class=\"wcorg-speaker wcorg-speaker-auxiliadora-martinez wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tAuxiliadora Mart\u00ednez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/298d70d7ffad8301545b8de3265fac7b94fd7aeb399d205264218cef9603127a?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/298d70d7ffad8301545b8de3265fac7b94fd7aeb399d205264218cef9603127a?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Ingeniera en computaci\u00f3n y cuenta con una maestr\u00eda en Sistemas de Informaci\u00f3n. Tiene m\u00e1s de 12 a\u00f1os de experiencia laboral. En su carrera ha tenido la oportunidad de trabajar con una gran variedad de tecnolog\u00edas tales como .NET, Java, Html, Css, Javascript, Angular, React, WordPress entre otros. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/auxiliadora-martinez\/#more-1213\" class=\"more-link\"><span aria-label=\"Sigue leyendo Auxiliadora Mart\u00ednez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-karol-perez\" class=\"wcorg-speaker wcorg-speaker-karol-perez wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tKarol P\u00e9rez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/41cb70d7e5bb6f91ce3a19aee74fe3ef1206490d521490005110753d38c84f57?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/41cb70d7e5bb6f91ce3a19aee74fe3ef1206490d521490005110753d38c84f57?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Periodista, licenciada en Comunicaci\u00f3n de Masas. Experiencia en redacci\u00f3n web, elaboraci\u00f3n y seguimiento de estrategias digitales, generaci\u00f3n de podcast multimedia, gesti\u00f3n de marcas en medios digitales y Redes Sociales. Coordinaci\u00f3n de generaci\u00f3n de contenido, edici\u00f3n de textos y QA de contenido period\u00edstico. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/karol-perez\/#more-1219\" class=\"more-link\"><span aria-label=\"Sigue leyendo Karol P\u00e9rez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-leo-jimenez\" class=\"wcorg-speaker wcorg-speaker-leo-jimenez\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tLeo Jimenez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/613b9887fceae9a386e6644205a3a3379b81d11d73d6c3ee416ab3e4694c584d?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/613b9887fceae9a386e6644205a3a3379b81d11d73d6c3ee416ab3e4694c584d?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Consultor en Inform\u00e1tica, Linux SysAdmin, Frond-end Web Developer. Miembro activo en la Comunidad de Software de la Universidad de Costa Rica. Brinda soporte a usuarios y personal TI en el Centro de Inform\u00e1tica de la Universidad de Costa Rica.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-abdel-atencio-valenciano\" class=\"wcorg-speaker wcorg-speaker-abdel-atencio-valenciano wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tAbdel Atencio Valenciano\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/727afc9a449f994a74c95f24610d824a7f2e10b4bb4e2dc04645953118fcadce?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/727afc9a449f994a74c95f24610d824a7f2e10b4bb4e2dc04645953118fcadce?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Abdel Atencio ha trabajado con tecnolog\u00edas basadas en Javascript durante 6 a\u00f1os, \u2028fue parte del equipo de investigaci\u00f3n de la agencia Digitas LBI (Digitas Labs) en el area de Javascript. Ha participado en foros dentro compa\u00f1\u00edas internacionales de gran renombre y fue mentor en el NodeSchool.\u2028<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/abdel-atencio-valenciano\/#more-1224\" class=\"more-link\"><span aria-label=\"Sigue leyendo Abdel Atencio Valenciano\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-ricardo-chamberlain\" class=\"wcorg-speaker wcorg-speaker-ricardo-chamberlain wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tRicardo Chamberlain Noboa\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/d0c62bf1f0ad36ac90fa5eeeb8fdbfa8352c5c0dba9a6492419aaf00a97fa4a8?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/d0c62bf1f0ad36ac90fa5eeeb8fdbfa8352c5c0dba9a6492419aaf00a97fa4a8?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Ricardo es un entusiasta en WordPress quien como todos ha aprendido sobre la marcha. Cuenta con experiencia administrando proyectos desarrollados en WordPress (y otros CMS) para agencias en Costa Rica con clientes en el extranjero as\u00ed como creando sitios web para cliente locales.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ricardo-chamberlain\/#more-1094\" class=\"more-link\"><span aria-label=\"Sigue leyendo Ricardo Chamberlain Noboa\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-ronny-freites\" class=\"wcorg-speaker wcorg-speaker-ronny-freites wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tRonny Freites\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/60f09f3cdf114c708ebb60ad5fe0c493ec0fb6b319b1343e0976a7b18d72a16d?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/60f09f3cdf114c708ebb60ad5fe0c493ec0fb6b319b1343e0976a7b18d72a16d?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Ingeniero de Sistemas Full Stack Developer en Hangar con amplia experiencia en desarrollo de software personalizado y aplicaciones web implementando patrones de dise\u00f1o. Fue voluntario en el Wordcamp San Jose Costa Rica 2016. Apasionado por el open source y el aprendizaje online.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ronny-freites\/#more-1185\" class=\"more-link\"><span aria-label=\"Sigue leyendo Ronny Freites\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-jackline-aurora-mejia\" class=\"wcorg-speaker wcorg-speaker-jackline-aurora-mejia wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJackline Aurora Mej\u00eda\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/1c1ab00c8bc4b0e8785b64a57a5f133cf7fec6409e95f1bcc438cbccc179ac49?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/1c1ab00c8bc4b0e8785b64a57a5f133cf7fec6409e95f1bcc438cbccc179ac49?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Jackline Aurora es actualmente una consultora de mercadeo que ha trabajado para compa\u00f1\u00edas de Fortune 500 y empresas de 500 startups. Maneja la parte de mercadeo digital, desde SEO, SEM, Social Media hasta growth hacking y tiene una pasi\u00f3n por crecer compa\u00f1\u00edas en linea.<br \/>\n <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/jackline-aurora-mejia\/#more-1066\" class=\"more-link\"><span aria-label=\"Sigue leyendo Jackline Aurora Mej\u00eda\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-rodrigo-donini\" class=\"wcorg-speaker wcorg-speaker-rodrigo-donini wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tRodrigo Donini\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/c8cf504e5ae3826eb87591aa4f6658e912bc658a0d8aa487ad90b4ce26ff7f24?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/c8cf504e5ae3826eb87591aa4f6658e912bc658a0d8aa487ad90b4ce26ff7f24?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Act\u00fao como desarrollador remotamente desde hace 8 a\u00f1os, trabajando en distintos proyectos desde los m\u00e1s sencillos a los m\u00e1s complejos. Empec\u00e9 a participar de conferencias luego que ingres\u00e9 en la universidad y desde ah\u00ed tuve la oportunidad de estar en numerosas charlas incluso en el ultimo WordCamp Porto Alegre 2017. <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/rodrigo-donini\/#more-1052\" class=\"more-link\"><span aria-label=\"Sigue leyendo Rodrigo Donini\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-lincy-gonzalez-rojas\" class=\"wcorg-speaker wcorg-speaker-lincy-gonzalez-rojas wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tLincy Gonz\u00e1lez Rojas\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/65ddc3a33c9db08be1585afbd31274fee3933091c60e1d27dbb1663496eb54f7?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Ingeniera en sistemas, con especialidad en desarrollo web y auditor\u00eda.\u00a0 Profesora de la Universidad Nacional desde hace 6 a\u00f1os, actualmente tambi\u00e9n labora para Stateside.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/lincy-gonzalez-rojas\/#more-1147\" class=\"more-link\"><span aria-label=\"Sigue leyendo Lincy Gonz\u00e1lez Rojas\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-mariana-lopez\" class=\"wcorg-speaker wcorg-speaker-mariana-lopez wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tMariana L\u00f3pez\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/19fef80ada791176db64e7838ecac74db00919c9b86a8bc1ba34cf793de43678?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/19fef80ada791176db64e7838ecac74db00919c9b86a8bc1ba34cf793de43678?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Mariana Lopez es la Directora de Product en Usabili.me, es una dise\u00f1adora de experiencias que ha dedicado su carrera a trabajar con equipos que dise\u00f1an, construyen y prueban productos utilizando un enfoque centrado en el usuario. <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/mariana-lopez\/#more-1172\" class=\"more-link\"><span aria-label=\"Sigue leyendo Mariana L\u00f3pez\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-waleska-oporta\" class=\"wcorg-speaker wcorg-speaker-waleska-oporta wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tWaleska Oporta\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/a87d39c11c4bd55cc356c81d784578209f1100837ab2f60fa22c8311ece1b68f?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/a87d39c11c4bd55cc356c81d784578209f1100837ab2f60fa22c8311ece1b68f?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Waleska Oporta es Publicista de ULACIT con 10 a\u00f1os de experiencia como especialista en SEO y Estrategia Digital. Ha trabajado con marcas como Aeropost, INCAE y Procomer, as\u00ed como en industrias tan competitivas como el online gaming, la log\u00edstica y el e-commerce.<\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/waleska-oporta\/#more-1244\" class=\"more-link\"><span aria-label=\"Sigue leyendo Waleska Oporta\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-karla-carvajal\" class=\"wcorg-speaker wcorg-speaker-karla-carvajal wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tKarla Carvajal\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/c64f0d4da99c62811bfdba3d1afa3412cb1613799335c05027453b221dfd9714?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/c64f0d4da99c62811bfdba3d1afa3412cb1613799335c05027453b221dfd9714?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Emprendedora, Relacionista p\u00fablica, fil\u00f3loga inglesa y cl\u00e1sica. Tiene experiencia en el \u00e1mbito de la comunicaci\u00f3n tanto oral como escrita, as\u00ed como de masas. Tiene m\u00e1s de dos a\u00f1os administrando p\u00e1ginas desarrolladas en WordPress. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/karla-carvajal\/#more-1215\" class=\"more-link\"><span aria-label=\"Sigue leyendo Karla Carvajal\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-salvador-aguilar\" class=\"wcorg-speaker wcorg-speaker-salvador-aguilar wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tSalvador Aguilar\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/88c3cc0dedae34414210edecce4a1872913cc98c837e76ba1a4dbe9ccea9a1fc?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/88c3cc0dedae34414210edecce4a1872913cc98c837e76ba1a4dbe9ccea9a1fc?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Es ingeniero sucuri con m\u00e1s de 10 a\u00f1os de experiencia en TI. Su especialidad es la gesti\u00f3n de la infraestructura web en hardware, as\u00ed como en la nube. Adem\u00e1s, se han colaborado con equipos multiling\u00fces a construir y escalar proyectos web como www.decompras.com, www.sears.com.mx, y otros. <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/salvador-aguilar\/#more-1062\" class=\"more-link\"><span aria-label=\"Sigue leyendo Salvador Aguilar\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-ashton-brown\" class=\"wcorg-speaker wcorg-speaker-ashton-brown wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tAshton Brown\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/e8a0e8ca918a32b6179f1f0b9c1c9d5200bfd468b35045c13cd1387fa8d9d809?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/e8a0e8ca918a32b6179f1f0b9c1c9d5200bfd468b35045c13cd1387fa8d9d809?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Ashton Brown ha estado trabajando como dise\u00f1ador web durante m\u00e1s de 20 a\u00f1os y enfocado a WordPress los \u00faltimos 10 a\u00f1os. Tiene experiencia con grandes equipos corporativos y con peque\u00f1as empresas, su misi\u00f3n siempre es ayudar a dise\u00f1ar y construir sitios web de maxima calidad. Pas\u00f3 la mayor parte de su carrera en Austin, Texas y ahora vive y trabaja en Tamarindo, Costa Rica. <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/ashton-brown\/#more-762\" class=\"more-link\"><span aria-label=\"Sigue leyendo Ashton Brown\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-jose-ramon-padron\" class=\"wcorg-speaker wcorg-speaker-jose-ramon-padron wcorg-track-la-cali wcorg-track-escalante\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJose Ramon Padr\u00f3n\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/b96138f8f41a63ffc23173ab3faa5e53ee0c39328a8fee3dcaa964d6c2bf6138?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/b96138f8f41a63ffc23173ab3faa5e53ee0c39328a8fee3dcaa964d6c2bf6138?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Es un apasionado de la atenci\u00f3n al cliente y las ventas centrado en los sectores del hosting y open source en Espa\u00f1a y LatAm desde hace 17 a\u00f1os. Devoto de la m\u00fasica rock, la gastronom\u00eda y la ciencia ficci\u00f3n desde hace muchos a\u00f1os m\u00e1s. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/jose-ramon-padron\/#more-1050\" class=\"more-link\"><span aria-label=\"Sigue leyendo Jose Ramon Padr\u00f3n\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-melissa-mata-arguello\" class=\"wcorg-speaker wcorg-speaker-melissa-mata-arguello wcorg-track-la-cali\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tMelissa Mata Arg\u00fcello\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/8a550d1499b6993da63593a4b0da96806448156dcb68d8a921dd8fddbe68034a?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/8a550d1499b6993da63593a4b0da96806448156dcb68d8a921dd8fddbe68034a?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Estudiante de  Inform\u00e1tica Empresarial y profesora en la Universidad de Costa Rica.<br \/>\nEntusiasta por la tecnolog\u00eda y el dise\u00f1o gr\u00e1fico. Creativa y polif\u00e9cetica. En constante aprendizaje de nuevas experiencias profesionales. <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/melissa-mata-arguello\/#more-1277\" class=\"more-link\"><span aria-label=\"Sigue leyendo Melissa Mata Arg\u00fcello\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<!-- Organizers note: The id attribute is deprecated and only remains for backwards compatibility, please use the corresponding class to target individual speakers -->\n\t\t\t<div id=\"wcorg-speaker-jose-pablo-murillo\" class=\"wcorg-speaker wcorg-speaker-jose-pablo-murillo wcorg-track-amon\">\n\t\t\t\t<h2>\n\t\t\t\t\t\n\t\t\t\t\t\tJose Pablo Murillo\n\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t<div class=\"wcorg-speaker-description\">\n\t\t\t\t\t<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/eb0def4cccd6a27f70c2de91a410648fe7c5958ed241c6fb9c1dded6ff846961?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/eb0def4cccd6a27f70c2de91a410648fe7c5958ed241c6fb9c1dded6ff846961?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' \/>\t\t\t\t\t<p>Jose Murillo es un apasionado por el marketing digital y los negocios. Estas dos pasiones y un incalmable deseo de aprender lo han llevado a especializarse en diferentes \u00e1reas relacionadas a estos temas, a participar activamente en comunidades de marketing digital y WordPress y  a desarrollar Animus. <\/p>\n<p> <a href=\"https:\/\/sanjose.wordcamp.org\/2017\/speaker\/jose-pablo-murillo\/#more-1121\" class=\"more-link\"><span aria-label=\"Sigue leyendo Jose Pablo Murillo\">(m\u00e1s&hellip;)<\/span><\/a><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7579285,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PheNhY-8","jetpack-related-posts":[{"id":162,"url":"https:\/\/sanjose.wordcamp.org\/2017\/organizadores\/","url_meta":{"origin":8,"position":0},"title":"Organizadores","author":"remediosgraphic","date":"junio 11, 2017","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/05\/cropped-cropped-logoWordCampSJ2017.png?fit=512%2C512&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":9,"url":"https:\/\/sanjose.wordcamp.org\/2017\/sessions\/","url_meta":{"origin":8,"position":1},"title":"Sessions","author":"elpuas","date":"marzo 31, 2017","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/05\/cropped-cropped-logoWordCampSJ2017.png?fit=512%2C512&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":2041,"url":"https:\/\/sanjose.wordcamp.org\/2017\/vip-dinner\/","url_meta":{"origin":8,"position":2},"title":"VIP dinner","author":"remediosgraphic","date":"agosto 15, 2017","format":false,"excerpt":"Queremos invitarte a compartir un rato antes del evento a la cena de voluntarios, speakers y sponsors, la misma se realizar\u00e1 el viernes 1 de septiembre a las 7:00pm en el restaurante Tin-Jo (Sal\u00f3n Bamb\u00fa, frente al teatro lucho barahona. Calle 11, ave 6 y 8, San Jos\u00e9.), el lugar\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/05\/cropped-cropped-logoWordCampSJ2017.png?fit=512%2C512&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":173,"url":"https:\/\/sanjose.wordcamp.org\/2017\/que-hacer-en-un-wordcamp\/","url_meta":{"origin":8,"position":3},"title":"\u00bfQu\u00e9 hacer en un WordCamp?","author":"remediosgraphic","date":"junio 11, 2017","format":false,"excerpt":"\u00bfQu\u00e9 hacer en un WordCamp? En\u00a0WCSJCR\u00a0podr\u00e1s aprender de los mejores, tendremos grandes speakers (incluso internacionales y developers del core de WordPress) que nos ense\u00f1ar\u00e1n las \u00faltimas novedades de WordPress y proyectos incre\u00edbles que se pueden realizar. En el WordCamp San Jos\u00e9 encontrar\u00e1s: Conocimiento 42 charlas\u00a0 con temas como JavaScript, PHP,\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/06\/cielo2.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/06\/cielo2.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/06\/cielo2.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/06\/cielo2.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":133,"url":"https:\/\/sanjose.wordcamp.org\/2017\/llamado-a-speakers\/","url_meta":{"origin":8,"position":4},"title":"Llamado a Speakers","author":"elpuas","date":"junio 11, 2017","format":false,"excerpt":"El a\u00f1o 2016 tuvimos nuestro primer WordCamp en Costa Rica, realizado en San Jos\u00e9, el cual fue todo un \u00e9xito y este a\u00f1o vamos por mucho m\u00e1s.\u00a0Queremos que sea un evento memorable y que seas parte de nuestra legendaria lista de expositores. Nos reuniremos el pr\u00f3ximo 2 y 3 de\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/05\/cropped-cropped-logoWordCampSJ2017.png?fit=512%2C512&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]},{"id":155,"url":"https:\/\/sanjose.wordcamp.org\/2017\/codigo-de-conducta\/","url_meta":{"origin":8,"position":5},"title":"C\u00f3digo de Conducta","author":"remediosgraphic","date":"junio 11, 2017","format":false,"excerpt":"Prop\u00f3sito WordCamp San Jos\u00e9, Costa Rica cree que nuestra comunidad debe estar abierta para todo el mundo. Como tal, estamos comprometidos a proporcionar un ambiente agradable, seguro y acogedor para todos, independientemente de su sexo, orientaci\u00f3n sexual, discapacidad, etnia, religi\u00f3n, sistema operativo preferido, lenguaje de programaci\u00f3n o editor de texto.\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2017\/files\/2017\/05\/cropped-cropped-logoWordCampSJ2017.png?fit=512%2C512&resize=350%2C200#038;ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/7579285"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":4,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":777,"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/pages\/8\/revisions\/777"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}