{"id":233,"date":"2016-08-29T21:23:51","date_gmt":"2016-08-29T21:23:51","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_sponsor&#038;p=233"},"modified":"2016-09-05T02:40:57","modified_gmt":"2016-09-05T02:40:57","slug":"dreamhost","status":"publish","type":"wcb_sponsor","link":"https:\/\/sanjose.wordcamp.org\/2016\/sponsor\/dreamhost\/","title":{"rendered":"DreamHost"},"content":{"rendered":"<div class=\"entry-content\">\n<p>Desde 1997 DreamHost ha ayudado individos, peque\u00f1as empresas, empresarios y desarrolladores de todo el mundo a llevar sus sue\u00f1os a la vida en el Internet. Empezando con los registros de dominio hasta el alojamiento web tradicional y WordPress logrado el mejor eviroment optimizada de alojamiento, m\u00e1s de 400.000 clientes conf\u00edan en DreamHost para ser su hogar en l\u00ednea. DreamHost apoya el proyecto de WordPress y la comunidad con recursos dedicados y un equipo apasionado. Un super paquete con una excelente relaci\u00f3n valor calidad, DreamHost es un gran lugar para poner en marcha un blog, sitio web o aplicaci\u00f3n en l\u00ednea a la estratosfera! M\u00e1s informaci\u00f3n en <a href=\"https:\/\/www.dreamhost.com\/\" rel=\"nofollow\">www.DreamHost.com<\/a><\/p>\n<hr>\n<p>Since 1997 DreamHost has helped individuals, small businesses, entrepreneurs and developers the world over bring their dreams to life on the Internet. From domain registrations to traditional web hosting and highly-optimized managed WordPress hosting, more than 400,000 customers trust DreamHost to be their online home. DreamHost supports the WordPress project and community with dedicated resources and a passionate team. Packed with excellent value, DreamHost is a great place to launch a blog, website, or online application into the stratosphere! Learn more at <a href=\"https:\/\/www.dreamhost.com\/\" rel=\"nofollow\">www.DreamHost.com<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desde 1997 DreamHost ha ayudado individos, peque\u00f1as empresas, empresarios y desarrolladores de todo el mundo a llevar sus sue\u00f1os a la vida en el Internet. Empezando con los registros de dominio hasta el alojamiento web tradicional y WordPress logrado el &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/sponsor\/dreamhost\/\">Continue reading <span class=\"assistive-text\">DreamHost<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"featured_media":262,"template":"","meta":{"_wcpt_sponsor_website":"https:\/\/www.dreamhost.com\/","footnotes":""},"sponsor_level":[10618],"class_list":["post-233","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-plata"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-3L","_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":5,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/233\/revisions"}],"predecessor-version":[{"id":542,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/233\/revisions\/542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media\/262"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=233"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsor_level?post=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}