{"id":229,"date":"2016-09-10T21:16:44","date_gmt":"2016-09-10T21:16:44","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_sponsor&#038;p=229"},"modified":"2016-09-24T20:43:52","modified_gmt":"2016-09-24T20:43:52","slug":"woocommerce","status":"publish","type":"wcb_sponsor","link":"https:\/\/sanjose.wordcamp.org\/2016\/sponsor\/woocommerce\/","title":{"rendered":"WooCommerce"},"content":{"rendered":"<div class=\"entry-content\">\n<p>WooCommerce es el software\/plataforma de e-commerce de m\u00e1s r\u00e1pido crecimiento, impulsando m\u00e1s del 30% de todas las tiendas en linea y con m\u00e1s de 1 mill\u00f3n de instalaciones activas. Est\u00e1 construido para integrarse perfectamente con WordPress, por lo que es la elecci\u00f3n obvia de e-commerce para los usuarios de WordPress, adem\u00e1s que se conecta con un ecosistema escalable de WordPress, el cual impulsa mas del 25% de todos los sitios web en Internet.<\/p>\n<p>Con WooCommerce ud puede empezar usando todas las herramientas b\u00e1sicas que habr\u00eda que cualquier peque\u00f1a empresa necesita para vender en l\u00ednea, incluyendo la configuraci\u00f3n del producto, los pagos, las opciones de env\u00edo, y los informes de ventas. Para que su negocio crezca ud puede elegir entre m\u00e1s de 300 complementos especiales disponibles, incluyendo el pago adicional procesadores, los m\u00e9todos de env\u00edo, sistemas de inventario y herramientas de marketing para vender cualquier cosa, en cualquier lugar de productos reales, descargas digitales, suscripciones, contenido e incluso su tiempo.<\/p>\n<p>En julio de 2015, WooCommerce fue adquirida por Automattic, los creadores de <a href=\"https:\/\/wordpress.com\" target=\"_blank\" rel=\"nofollow\"> WordPress.com <\/a> que el el motor de m\u00e1s de 15,8 mil millones de p\u00e1ginas al mes y tambi\u00e9n creadores de otros servicios populares como WordPress Akismet, Jetpack, y VaultPress. Esperamos crecer mas en WooCommerce para lograr cosas a\u00fan m\u00e1s grandes, junto con Automattic.<\/p>\n<hr \/>\n<p>WooCommerce is the fastest growing eCommerce software\/platform, powering over 30% of all eCommerce stores with over 1 million active installations. It is is built to integrate seamlessly with WordPress, making it the obvious eCommerce choice for existing WordPress users and connects you to the fast-growing WordPress ecosystem which now powers over 25% of all websites on the internet.<\/p>\n<p>With WooCommerce you can start with all the basic tools that any small business would need to start selling online, including product setup, payments, shipping options, and sales reports and as your business grows choose from over 300 premium add-ons available including additional payment processors, shipping methods, inventory systems and marketing tools anyone to sell anything, anywhere from real products and digital downloads to subscriptions, content and even your time.<\/p>\n<p>In July 2015, WooCommerce was acquired by Automattic, the creators of <a href=\"https:\/\/wordpress.com\" target=\"_blank\" rel=\"nofollow\">WordPress.com<\/a> which serves more than 15.8 billion pages a month and also the creators of other popular WordPress services including Akismet, Jetpack, and VaultPress. We look forward to growing WooCommerce to achieve even greater things together with Automattic.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>WooCommerce es el software\/plataforma de e-commerce de m\u00e1s r\u00e1pido crecimiento, impulsando m\u00e1s del 30% de todas las tiendas en linea y con m\u00e1s de 1 mill\u00f3n de instalaciones activas. Est\u00e1 construido para integrarse perfectamente con WordPress, por lo que es &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/sponsor\/woocommerce\/\">Continue reading <span class=\"assistive-text\">WooCommerce<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"featured_media":258,"template":"","meta":{"_wcpt_sponsor_website":"https:\/\/woocommerce.com\/","footnotes":""},"sponsor_level":[10616],"class_list":["post-229","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-platino"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-3H","_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":8,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/229\/revisions"}],"predecessor-version":[{"id":762,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/229\/revisions\/762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media\/258"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=229"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsor_level?post=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}