{"id":1644,"date":"2016-11-02T18:07:50","date_gmt":"2016-11-02T18:07:50","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1644"},"modified":"2016-11-02T18:20:23","modified_gmt":"2016-11-02T18:20:23","slug":"eduardo-enzo-garcia","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/eduardo-enzo-garcia\/","title":{"rendered":"Eduardo Enzo Garcia"},"content":{"rendered":"<p>Su nombre es Eduardo Garc\u00eda, pero conocido como &#8220;enzo&#8221; en comunidades de c\u00f3digo abierto. Knowmad por definici\u00f3n y viajero por convicci\u00f3n.  Cofundador y CTO de Anexus, un taller Drupal ubicado en Costa Rica, que presta servicios a agencias ubicadas en Estados Unidos, Canad\u00e1 y Europa.<!--more--><\/p>\n<p>Dos veces candidato a &#8220;Director en general en la Asociaci\u00f3n Drupal&#8221; con uno de los m\u00e1s altos niveles de participaci\u00f3n, sin descartar la intenci\u00f3n de volver a correr el pr\u00f3ximo a\u00f1o para ello.<br \/>\nDesarrollador web desde 1996 y usuario de Drupal desde 2008, l\u00edder de Costa Rica Drupal Community, coorganizando de seis Drupal Camps en Costa Rica, convirti\u00e9ndo al mismo en el m\u00e1s tradicional y uno de los mayores eventos de Drupal en Latinoam\u00e9rica.<br \/>\nEnzo tiene una visi\u00f3n global de la comunidad (web, no solo drupal), por eso ha participado en 6 Drupal Cons, 21 Drupal Camps y decenes de encuentros en 4 continentes. Su \u00faltima aventura fue Viajar por el Mundo Drupal en m\u00e1s de 140 d\u00edas, con el objetivo de promover y compartir el uso de Drupal 8 y el proyecto Drupal Console en todo el mundo.<br \/>\nSu \u00faltima empresa es WeKnow una empresa para proporcionar tren y asesoramiento en Drupal 8 y aplicaciones Symfony.<br \/>\nPuede leer m\u00e1s sobre Enzo en:<br \/>\nenzolutions.com<br \/>\nanexusit.com<br \/>\nweknowinc.com<\/p>\n<hr>\n<p>Named as Eduardo Garcia, but knows as &#8220;enzo&#8221; in open source communities. Knowmad by definition and traveler by conviction<br \/>\nCo-founder and CTO of Anexus, a Drupal workshop located in Costa Rica, providing services for agencies located in USA, Canada, and Europe.<br \/>\nTwo times candidate for &#8220;Director at Large in Drupal Association&#8221; with one of the highest turnout, without discard the intention to run again next year for it.<br \/>\nWeb developer from 1996 and Drupal User since 2008, leader of Costa Rica Drupal Community, co-organing six Drupal Camps in Costa Rica, becoming in the most traditional and one of the biggest Drupal events in Latin America.<br \/>\nEnzo has a global vision of community, for that reason he has participated in 6 Drupal Cons, 21 Drupal Camps, and decenes of meetups in 4 continents. His last adventure was Travel around the Drupal World in 140+ days, with the objective of promoting and share the usage of Drupal 8 and Drupal Console project around the world.<br \/>\nHis last enterprise is weKnow a company to provide train and advisory in Drupal 8 and Symfony applications.<br \/>\nYou can read more about Enzo at:<br \/>\nenzolutions.com<br \/>\nanexusit.com<br \/>\nweknowinc.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su nombre es Eduardo Garc\u00eda, pero conocido como &#8220;enzo&#8221; en comunidades de c\u00f3digo abierto. Knowmad por definici\u00f3n y viajero por convicci\u00f3n. Cofundador y CTO de Anexus, un taller Drupal ubicado en Costa Rica, que presta servicios a agencias ubicadas en &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/eduardo-enzo-garcia\/\">Continue reading <span class=\"assistive-text\">Eduardo Enzo Garcia<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"","footnotes":""},"speaker_group":[],"class_list":["post-1644","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-qw","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3dafa1e78f0915504891c1d10a21acf2108c98664577eadde4d900fa8841f2a9?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3dafa1e78f0915504891c1d10a21acf2108c98664577eadde4d900fa8841f2a9?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3dafa1e78f0915504891c1d10a21acf2108c98664577eadde4d900fa8841f2a9?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/3dafa1e78f0915504891c1d10a21acf2108c98664577eadde4d900fa8841f2a9?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/3dafa1e78f0915504891c1d10a21acf2108c98664577eadde4d900fa8841f2a9?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/3dafa1e78f0915504891c1d10a21acf2108c98664577eadde4d900fa8841f2a9?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1644"}],"version-history":[{"count":2,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1644\/revisions"}],"predecessor-version":[{"id":1648,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1644\/revisions\/1648"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/1179?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1644"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speaker_group?post=1644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}