{"id":1641,"date":"2016-11-02T17:57:52","date_gmt":"2016-11-02T17:57:52","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1641"},"modified":"2016-11-02T17:57:52","modified_gmt":"2016-11-02T17:57:52","slug":"mario-quiros","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/mario-quiros\/","title":{"rendered":"Mario Quir\u00f3s"},"content":{"rendered":"<p>Trabajo como desarrollador en tecnolog\u00eda web, actualmente en vivo en Costa Rica y trabajo para algunas empresas internacionales como freelance. Apasionado por la plataforma WordPress y trabajando en comunidades activas para esparcir el conocimiento.<\/p>\n<hr \/>\n<p>Working as a developer in web technology, currently live and work in Costa Rica for some international companies as a freelance. Fascinated by WordPress platform and working in active communities to spread the knowledge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajo como desarrollador en tecnolog\u00eda web, actualmente en vivo en Costa Rica y trabajo para algunas empresas internacionales como freelance. Apasionado por la plataforma WordPress y trabajando en comunidades activas para esparcir el conocimiento. Working as a developer in web &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/mario-quiros\/\">Continue reading <span class=\"assistive-text\">Mario Quir\u00f3s<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"mhackredcom","footnotes":""},"speaker_group":[],"class_list":["post-1641","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-qt","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/c7940625328c6cb6b77f7f07eba97510c25c0ae288c3f80c802a7c336be628a3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/c7940625328c6cb6b77f7f07eba97510c25c0ae288c3f80c802a7c336be628a3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/c7940625328c6cb6b77f7f07eba97510c25c0ae288c3f80c802a7c336be628a3?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/c7940625328c6cb6b77f7f07eba97510c25c0ae288c3f80c802a7c336be628a3?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/c7940625328c6cb6b77f7f07eba97510c25c0ae288c3f80c802a7c336be628a3?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/c7940625328c6cb6b77f7f07eba97510c25c0ae288c3f80c802a7c336be628a3?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1641"}],"version-history":[{"count":1,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1641\/revisions"}],"predecessor-version":[{"id":1643,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1641\/revisions\/1643"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/780?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1641"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speaker_group?post=1641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}