{"id":1103,"date":"2016-10-08T04:00:32","date_gmt":"2016-10-08T04:00:32","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1103"},"modified":"2016-10-08T04:02:33","modified_gmt":"2016-10-08T04:02:33","slug":"sebastian-gomez","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/sebastian-gomez\/","title":{"rendered":"Sebasti\u00e1n G\u00f3mez"},"content":{"rendered":"<p>Sebasti\u00e1n G\u00f3mez es un emprendedor de 20 a\u00f1os especializado en el mercadeo por Internet. Desde los 16 a\u00f1os Sebastian descubri\u00f3 el potencial en esta \u00e1rea ya que la mayor\u00eda de ventas se generan a travez de plataformas en l\u00ednea. Siempre ha tenido en cuenta que la forma m\u00e1s r\u00e1pida de generar resultados es a trav\u00e9s de tr\u00e1fico pagado. Sin embargo, con el tiempo ha aprendido que el tr\u00e1fico por si solo no tiene mucho valor. Por esta raz\u00f3n aprendi\u00f3 como utilizar las diferentes plataformas sociales para convertir ese tr\u00e1fico en ventas, y de esta forma crear m\u00faltiples negocios exitosos.<br \/>\n<!--more--><\/p>\n<p>Sebasti\u00e1n ha ayudado a docenas de personas e inclusive empresas internacionales a conseguir m\u00e1s clientes a trav\u00e9s de publicidad pagada de Facebook y aumentar su rentabilidad con estrategias que funcionan en la actualidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sebasti\u00e1n G\u00f3mez es un emprendedor de 20 a\u00f1os especializado en el mercadeo por Internet. Desde los 16 a\u00f1os Sebastian descubri\u00f3 el potencial en esta \u00e1rea ya que la mayor\u00eda de ventas se generan a travez de plataformas en l\u00ednea. Siempre &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/sebastian-gomez\/\">Continue reading <span class=\"assistive-text\">Sebasti\u00e1n G\u00f3mez<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"","footnotes":""},"speaker_group":[],"class_list":["post-1103","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-hN","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/e14f406ba7cf4e53306e73d1423e0aed76ab73c684f324a41a752b3701016797?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/e14f406ba7cf4e53306e73d1423e0aed76ab73c684f324a41a752b3701016797?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/e14f406ba7cf4e53306e73d1423e0aed76ab73c684f324a41a752b3701016797?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/e14f406ba7cf4e53306e73d1423e0aed76ab73c684f324a41a752b3701016797?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/e14f406ba7cf4e53306e73d1423e0aed76ab73c684f324a41a752b3701016797?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/e14f406ba7cf4e53306e73d1423e0aed76ab73c684f324a41a752b3701016797?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1103"}],"version-history":[{"count":1,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1103\/revisions"}],"predecessor-version":[{"id":1104,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1103\/revisions\/1104"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/1033?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1103"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speaker_group?post=1103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}