{"id":1096,"date":"2016-10-08T03:50:19","date_gmt":"2016-10-08T03:50:19","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_speaker&#038;p=1096"},"modified":"2016-10-08T03:58:59","modified_gmt":"2016-10-08T03:58:59","slug":"paula-hidalgo","status":"publish","type":"wcb_speaker","link":"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/paula-hidalgo\/","title":{"rendered":"Paula Hidalgo"},"content":{"rendered":"<p>Paula Hidalgo-Calvo se gradu\u00f3 como ingeniera en Dise\u00f1o Industrial del Instituto Tecnol\u00f3gico de Costa Rica. Curs\u00f3 un semestre en la carrera de Intermedia en la Fachhochschule Vorarlberg en Austria. Tiene tres a\u00f1os de experiencia como UX Designer y ha trabajado previamente como dise\u00f1adora visual. Paula se dedica al dise\u00f1o centrado en el usuario y tiene experiencia en arquitectura de la informaci\u00f3n, estudio de usuarios y pruebas de usabilidad, principalmente en experiencias digitales.<\/p>\n<p><!--more--><br \/>\nActualmente es parte de Possible Costa Rica. Sus proyectos abarcan diferentes \u00e1reas como banca, sistemas para manejo de contenido, industria musical y sitios informativos, entre otras. Ha trabajado con clientes a nivel regional e internacional.<\/p>\n<hr>\n<p>Paula Hidalgo-Calvo graduated as an industrial design engineer, at the Costa Rica Institute of Technology. She took a semester at the career of Intermedia at the Fachhochschule Vorarlberg in Austria. She has three years of experience as a UX Designer and has worked before as a visual designer.<\/p>\n<p>Paula focuses on user-centered design and has experience with information architecture, user research and usability testing, mainly on digital experiences. She&#8217;s currently part of Possible Costa Rica. Her projects cover different areas such as banking, content management systems, musical industry and informational sites, among others. She has worked with regional and international clients.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paula Hidalgo-Calvo se gradu\u00f3 como ingeniera en Dise\u00f1o Industrial del Instituto Tecnol\u00f3gico de Costa Rica. Curs\u00f3 un semestre en la carrera de Intermedia en la Fachhochschule Vorarlberg en Austria. Tiene tres a\u00f1os de experiencia como UX Designer y ha trabajado &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/paula-hidalgo\/\">Continue reading <span class=\"assistive-text\">Paula Hidalgo<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"","footnotes":""},"speaker_group":[],"class_list":["post-1096","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-hG","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/aec40a79eae5f3019c38f723ce806d21c011fc0b8bc6dd4a1d8adb7f5b68c96b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/aec40a79eae5f3019c38f723ce806d21c011fc0b8bc6dd4a1d8adb7f5b68c96b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/aec40a79eae5f3019c38f723ce806d21c011fc0b8bc6dd4a1d8adb7f5b68c96b?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/aec40a79eae5f3019c38f723ce806d21c011fc0b8bc6dd4a1d8adb7f5b68c96b?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/aec40a79eae5f3019c38f723ce806d21c011fc0b8bc6dd4a1d8adb7f5b68c96b?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/aec40a79eae5f3019c38f723ce806d21c011fc0b8bc6dd4a1d8adb7f5b68c96b?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=1096"}],"version-history":[{"count":4,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1096\/revisions"}],"predecessor-version":[{"id":1102,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1096\/revisions\/1102"}],"sessions":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/1045?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1096"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speaker_group?post=1096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}