{"id":972,"date":"2016-10-07T06:51:58","date_gmt":"2016-10-07T06:51:58","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_session&#038;p=972"},"modified":"2016-10-10T16:28:11","modified_gmt":"2016-10-10T16:28:11","slug":"headless-wp-en-mobile-apps-ios-android-nativo","status":"publish","type":"wcb_session","link":"https:\/\/sanjose.wordcamp.org\/2016\/session\/headless-wp-en-mobile-apps-ios-android-nativo\/","title":{"rendered":"Headless WP en Mobile Apps iOS-Android nativo."},"content":{"rendered":"<p>Introducci\u00f3n a Headless WordPress. Presentaci\u00f3n de caso base a desarrollar como Aplicaci\u00f3n mobile. Fortalezas de headless WP como recurso para Aplicaciones nativas. Soluci\u00f3n al caso utilizando Headless WordPress y su consumo en c\u00f3digo nativo.  Conclusiones y mejores pr\u00e1cticas al desarrollar utilizando Headless WordPress.<\/p>\n<p><!--more--><\/p>\n<hr>\n<p>Introduction to WordPress Headless. Presentation of a case base to  develop as mobile application. WP headless strengths as a resource for native applications. Solution to the case using Headless WordPress and consumption in native code. Conclusions and best practices in developing using Headless WordPress.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introducci\u00f3n a Headless WordPress. Presentaci\u00f3n de caso base a desarrollar como Aplicaci\u00f3n mobile. Fortalezas de headless WP como recurso para Aplicaciones nativas. Soluci\u00f3n al caso utilizando Headless WordPress y su consumo en c\u00f3digo nativo. Conclusiones y mejores pr\u00e1cticas al desarrollar &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/session\/headless-wp-en-mobile-apps-ios-android-nativo\/\">Continue reading <span class=\"assistive-text\">Headless WP en Mobile Apps iOS-Android nativo.<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":319559,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1478353500,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[970],"footnotes":""},"session_track":[5041],"session_category":[],"class_list":["post-972","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-developer"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-fG","session_date_time":{"date":"November 5, 2016","time":"1:45 pm"},"session_speakers":[{"id":"970","slug":"brian-rojas","name":"Brian Rojas","link":"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/brian-rojas\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/319559"}],"version-history":[{"count":3,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/972\/revisions"}],"predecessor-version":[{"id":1233,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/972\/revisions\/1233"}],"speakers":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/970"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=972"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/session_track?post=972"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/session_category?post=972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}