{"id":1045,"date":"2016-10-08T01:33:26","date_gmt":"2016-10-08T01:33:26","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?post_type=wcb_session&#038;p=1045"},"modified":"2016-10-10T16:26:37","modified_gmt":"2016-10-10T16:26:37","slug":"say-hello-to-my-little-friend-task-oriented-design","status":"publish","type":"wcb_session","link":"https:\/\/sanjose.wordcamp.org\/2016\/session\/say-hello-to-my-little-friend-task-oriented-design\/","title":{"rendered":"Say hello to my little friend: task oriented design."},"content":{"rendered":"<p>Imagine que se encuentra en el aeropuerto y pierde su vuelo. No hay internet y necesita hacer un cambio en la reservaci\u00f3n de su hotel para no perder su dinero. Se le ocurre ir a McDonald\u2019s y usar su red compartida. Cuando entra al sitio del hotel desde su tel\u00e9fono, con 20% de bater\u00eda y compartiendo la red con otras 50 personas, encuentra una galer\u00eda de fotos, la cual no s\u00f3lo consume la poca bater\u00eda que queda sino que dura una vida cargando.<\/p>\n<p><!--more--><\/p>\n<p>Adem\u00e1s debe iniciar sesi\u00f3n, buscar d\u00f3nde puede cambiar la reservaci\u00f3n y llenar un formulario de 10 campos. Le tom\u00f3 20 minutos, y se le fue la bater\u00eda. Qu\u00e9 pasar\u00eda si al abrir el sitio en su tel\u00e9fono hubiera encontrado dos botones prominentes: \u00bfDESEA RESERVAR? y PROBLEMAS CON SU RESERVACI\u00d3N.<\/p>\n<p>Para mejorar la experiencia del usuario seg\u00fan el dispositivo en el que se encuentre, el responsive design no siempre es la mejor opci\u00f3n desde el punto de vista de la usabilidad.<\/p>\n<p>Quisi\u00e9ramos hablarles sobre el Task Oriented Design: Task oriented design vs responsive design<\/p>\n<p>Cu\u00e1ndo usarlo y por qu\u00e9 es importante?<\/p>\n<p>Modelos de uso (usage models)<\/p>\n<p>C\u00f3mo definir y priorizar tareas?<\/p>\n<p>No asumir nada.<\/p>\n<p>User research y data.<\/p>\n<hr \/>\n<p>Imagine you are at the airport and miss your flight. No internet and need to make a change in booking your hotel to avoid losing your money. It occurs go to McDonald&#8217;s and use their shared network. When you enter the hotel room from your phone, with 20% battery and network sharing with 50 other people, find a photo gallery, which not only consumes little but remaining battery life lasts one loading.<\/p>\n<p>In addition you must log, look for where you can change the reservation and fill out a 10 fields. It took 20 minutes, and it was the battery. What if when you open your phone the site had found two prominent buttons: WANT TO BOOK? and PROBLEMS WITH YOUR RESERVATION.<\/p>\n<p>To improve the user experience depending on the device in which it is found, responsive design is not always the best choice from the point of view of usability.<\/p>\n<p>We would like to talk about the Task Oriented Design: Task oriented design vs Responsive Design<\/p>\n<p>When to use it and why is it important?<\/p>\n<p>Models of use (usage models)<\/p>\n<p>How to define and prioritize tasks?<\/p>\n<p>Do not assume anything.<\/p>\n<p>User research and data.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagine que se encuentra en el aeropuerto y pierde su vuelo. No hay internet y necesita hacer un cambio en la reservaci\u00f3n de su hotel para no perder su dinero. Se le ocurre ir a McDonald\u2019s y usar su red &hellip; <a href=\"https:\/\/sanjose.wordcamp.org\/2016\/session\/say-hello-to-my-little-friend-task-oriented-design\/\">Continue reading <span class=\"assistive-text\">Say hello to my little friend: task oriented design.<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":319559,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1478362500,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[1096],"footnotes":""},"session_track":[174],"session_category":[],"class_list":["post-1045","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-designer"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-gR","session_date_time":{"date":"November 5, 2016","time":"4:15 pm"},"session_speakers":[{"id":"1096","slug":"paula-hidalgo","name":"Paula Hidalgo","link":"https:\/\/sanjose.wordcamp.org\/2016\/speaker\/paula-hidalgo\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/1045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/319559"}],"version-history":[{"count":7,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/1045\/revisions"}],"predecessor-version":[{"id":1226,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/sessions\/1045\/revisions\/1226"}],"speakers":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/speakers\/1096"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=1045"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/session_track?post=1045"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/session_category?post=1045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}