{"id":665,"date":"2016-09-10T23:30:37","date_gmt":"2016-09-10T23:30:37","guid":{"rendered":"http:\/\/2016.sanjose.wordcamp.org\/?p=665"},"modified":"2016-09-10T23:44:25","modified_gmt":"2016-09-10T23:44:25","slug":"top-plugins-para-creadores-de-contenido-en-wordpress","status":"publish","type":"post","link":"https:\/\/sanjose.wordcamp.org\/2016\/top-plugins-para-creadores-de-contenido-en-wordpress\/","title":{"rendered":"Top plugins para escritores"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"669\" data-permalink=\"https:\/\/sanjose.wordcamp.org\/2016\/top-plugins-para-creadores-de-contenido-en-wordpress\/worpress-periodistas-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/09\/worpress-periodistas-1.jpg?fit=764%2C447&amp;ssl=1\" data-orig-size=\"764,447\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"worpress-periodistas\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/09\/worpress-periodistas-1.jpg?fit=640%2C374&amp;ssl=1\" class=\"aligncenter size-full wp-image-669\" src=\"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/09\/worpress-periodistas-1.jpg?resize=640%2C374\" alt=\"worpress-periodistas\" width=\"640\" height=\"374\" srcset=\"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/09\/worpress-periodistas-1.jpg?w=764&amp;ssl=1 764w, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/09\/worpress-periodistas-1.jpg?resize=300%2C176&amp;ssl=1 300w, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/09\/worpress-periodistas-1.jpg?resize=500%2C293&amp;ssl=1 500w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Seleccionamos una serie de herramientas muy necesarias dentro de nuestros sitios WordPress, si las conocen pueden compartirlas y si no las utilizaron antes, es el momento de ponerlas a prueba.<br \/>\n<!--more--><br \/>\n<strong>RB Internal Links<\/strong><\/p>\n<p>Esta herramienta hace posible la conexi\u00f3n de p\u00e1ginas y art\u00edculos sin introducir una sola l\u00ednea de c\u00f3digo e incluso sin colocar la direcci\u00f3n completa.<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>Contact Form 7<\/strong><\/p>\n<p>Es uno de los plugin m\u00e1s famosos de WordPress con m\u00e1s de 1 mill\u00f3n de instalaciones activas, es un creador de formularios de contacto, listas de correo electr\u00f3nico; es sencillo, pr\u00e1ctico y muy personalizable.<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>Broken Link Checker<\/strong><\/p>\n<p>Nada m\u00e1s irritante que hacer click en links rotos, no conducen a ninguna parte. El plugin Broken Link Checker es la soluci\u00f3n a este recurrente problema. La funci\u00f3n principal de esta herramienta es revisar constantemente el sitio para evitar los enlaces rotos y permite saber cu\u00e1ndo se encuentra uno para que pueda corregirse<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>Digg Digg<\/strong><\/p>\n<p>Su principal funci\u00f3n es ofrecer a los visitantes y lectores la facilidad de poder compartir los contenidos del blog en las diferentes redes sociales y con ello los art\u00edculos pueden alcanzar mayor visibilidad.<\/p>\n<pre>Nivel de Configuraci\u00f3n: Medio.<\/pre>\n<p><strong>Google Doc Embedder<\/strong><\/p>\n<p>El plugin de Google Doc Embebedor permite incluir archivos PDF o .docs en sus p\u00e1ginas usando el visor de Google. Tambi\u00e9n tiene la opci\u00f3n de permitir descargas de contenido. Este es un plugin incre\u00edble para los escritores porque se pueden compartir f\u00e1cilmente documentos con sus lectores.<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>Copyright Proof<\/strong><\/p>\n<p>Este plugin ofrece la certificaci\u00f3n de derechos de autor para cada pieza de contenido que usted publique en el sitio que haga con WordPress.<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>EditFlow<\/strong><\/p>\n<p>EditFlow act\u00faa como su propio equipo editorial, se puede personalizar para tareas espec\u00edficas. Sus caracter\u00edsticas incluyen un calendario de contenido, estados personalizados, comentarios editoriales, presupuestos, y grupos de usuarios.<\/p>\n<pre>Nivel de Configuraci\u00f3n: Medio.<\/pre>\n<p><strong>Yoast SEO y Analitics<\/strong><\/p>\n<p>Yoast es un plugin muy \u00fatil, al crear entradas en el blog le ayuda a organizar las palabras clave y datos importantes para mejorar el posicionamiento en buscadores.<\/p>\n<p>Yoast Google Analytics es una potente herramienta de seguimiento que analiza el tr\u00e1fico que recibimos, para llevar nuestros objetivos al siguiente nivel.<\/p>\n<pre>Nivel de Configuraci\u00f3n: Medio.<\/pre>\n<p><strong>Scribe<\/strong><\/p>\n<p>Scribe optimiza el contenido para la web mediante el an\u00e1lisis de las p\u00e1ginas, blogs y el tr\u00e1fico de los motores de b\u00fasqueda. Si alguna vez ha luchado para entender el papel de las palabras clave (keywords), encabezados, metadatos y etiquetado de medios, Scribe podr\u00eda ser su mejor amigo.<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>Wassup<\/strong><\/p>\n<p>Wassup cuenta con una consola de administraci\u00f3n que le permite mantener un ojo en las visitas, todo en tiempo real. La una idea es saber lo que hacen los lectores en su blog. Esto incluye proporcionar detalles de los visitantes, geo-localizaci\u00f3n, visitantes en l\u00ednea y mucho m\u00e1s<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>BuddyPress<\/strong><\/p>\n<p>BuddyPress es m\u00e1s de un plugin para crear una red social, BuddyPress b\u00e1sicamente convierte tu blog en un Facebook en miniatura. Los visitantes pueden registrarse y crear un perfil, enviar mensajes, conectarse con otros, y construir grupos.<\/p>\n<pre>Nivel de Configuraci\u00f3n: Medio.<\/pre>\n<p><strong>LinkWithin<\/strong><\/p>\n<p>Es un plugin muy \u00fatil para mostrar otras entradas del blog debajo de cada post. Con eso nos aseguramos de que los art\u00edculos tengan buena visibilidad y una muy buena presentaci\u00f3n.<\/p>\n<pre>Nivel de Configuraci\u00f3n: B\u00e1sico.<\/pre>\n<p><strong>Published Articles Since Last Visit<\/strong><\/p>\n<p>Este plugin funciona espec\u00edficamente para asegurarse que a los lectores que regresan est\u00e1n viendo contenidos en los que pueden estar m\u00e1s interesados . Esto se logra mediante la configuraci\u00f3n de avisos, Google Analytics y Feedburner.<\/p>\n<pre>Nivel de Configuraci\u00f3n: Medio.<\/pre>\n<p>Esperamos que las herramientas anteriores sean de utilidad y puedan ayudarles a solucionar alguna necesidad.<\/p>\n<p>Desde la organizaci\u00f3n del WordCamp Costa Rica, queremos invitarlos a ser parte del gran evento el 5 y 6 de Noviembre de 2016, pueden seguirnos en todas nuestras redes sociales y participar de manera activa con nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seleccionamos una serie de herramientas muy necesarias dentro de nuestros sitios WordPress, si las conocen pueden compartirlas y si no las utilizaron antes, es el momento de ponerlas a prueba.<\/p>\n","protected":false},"author":319559,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[28868,975773,3,35660,14],"tags":[],"class_list":["post-665","post","type-post","status-publish","format-standard","hentry","category-bloggers","category-comunicadores","category-news","category-recursos","category-wordpress"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMSH-aJ","jetpack-related-posts":[{"id":1268,"url":"https:\/\/sanjose.wordcamp.org\/2016\/meetup-como-crear-un-plugin\/","url_meta":{"origin":665,"position":0},"title":"Meetup como crear un plugin.","author":"remediosgraphic","date":"October 12, 2016","format":false,"excerpt":"Los plugins son una serie de programas que a\u00f1aden funciones nuevas a tu instalaci\u00f3n, es decir, componentes de c\u00f3digo que se instalan en WordPress para ampliar su funcionalidad est\u00e1ndar. Hay de todo tipo: desde los m\u00e1s simples que te permiten a\u00f1adir una referencia en un widget, hasta plataformas de ecommerce\u2026","rel":"","context":"In &quot;Meetup&quot;","block_context":{"text":"Meetup","link":"https:\/\/sanjose.wordcamp.org\/2016\/category\/wordpress\/meetup\/"},"img":{"alt_text":"campBlogCoworking","src":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/campBlogCoworking.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/campBlogCoworking.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/campBlogCoworking.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/campBlogCoworking.jpg?resize=700%2C400 2x"},"classes":[]},{"id":1361,"url":"https:\/\/sanjose.wordcamp.org\/2016\/meetup-acf-en-stateside-co\/","url_meta":{"origin":665,"position":1},"title":"Meetup ACF en Stateside Co.","author":"remediosgraphic","date":"October 15, 2016","format":false,"excerpt":"Para crear un tema a medida en WordPress, un plugin que no puede faltar es Advanced Custom Fields. Este plugin ayuda a personalizar WordPress a otro nivel y mejorar la interacci\u00f3n con el usuario. Advanced Custom Fields es un plugin gratis con mucho alcance desarrollado por Elliot Condon, el mismo\u2026","rel":"","context":"In &quot;Meetup&quot;","block_context":{"text":"Meetup","link":"https:\/\/sanjose.wordcamp.org\/2016\/category\/wordpress\/meetup\/"},"img":{"alt_text":"meetupStateside","src":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/meetupStateside-2.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/meetupStateside-2.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/meetupStateside-2.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/meetupStateside-2.jpg?resize=700%2C400 2x"},"classes":[]},{"id":695,"url":"https:\/\/sanjose.wordcamp.org\/2016\/llamado-a-voluntarios\/","url_meta":{"origin":665,"position":2},"title":"Llamado a Voluntarios","author":"remediosgraphic","date":"September 16, 2016","format":false,"excerpt":"Este a\u00f1o se realizar\u00e1 por primera vez en Costa Rica el WordCamp San Jos\u00e9, esta actividad consiste en una serie de charlas relacionadas con la plataforma de publicaci\u00f3n web m\u00e1s popular del mundo, WordPress. El evento tiene como objetivos, difundir el desarrollo local de WordPress, intercambiar experiencias, elevar el profesionalismo,\u2026","rel":"","context":"In &quot;news&quot;","block_context":{"text":"news","link":"https:\/\/sanjose.wordcamp.org\/2016\/category\/news\/"},"img":{"alt_text":"wordcampvoluntarios","src":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/09\/WordCampVoluntarios.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/09\/WordCampVoluntarios.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/09\/WordCampVoluntarios.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/09\/WordCampVoluntarios.jpg?resize=700%2C400 2x"},"classes":[]},{"id":1418,"url":"https:\/\/sanjose.wordcamp.org\/2016\/disenando-para-wordpress\/","url_meta":{"origin":665,"position":3},"title":"Dise\u00f1ando para WordPress","author":"elpuas","date":"October 20, 2016","format":false,"excerpt":"Ayer nos encontramos nuevamente muchos de la comunidad WordPress de Costa Rica, en esta ocasi\u00f3n Roberto Remedios, nos dio una muy buena invitaci\u00f3n al evento WordCamp Costa Rica, destacando las bondades de ir al evento en la Universidad de Costa Rica, 27 charlas, contenido invaluable, grandes patrocinadores y un fabuloso\u2026","rel":"","context":"In &quot;news&quot;","block_context":{"text":"news","link":"https:\/\/sanjose.wordcamp.org\/2016\/category\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/10\/6f7c0543-e919-47e5-b35d-12c221abaf0a.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/10\/6f7c0543-e919-47e5-b35d-12c221abaf0a.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/10\/6f7c0543-e919-47e5-b35d-12c221abaf0a.jpeg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/sanjose.wordcamp.org\/2016\/files\/2016\/10\/6f7c0543-e919-47e5-b35d-12c221abaf0a.jpeg?resize=700%2C400 2x"},"classes":[]},{"id":176,"url":"https:\/\/sanjose.wordcamp.org\/2016\/llamado-de-sponsors-para-wordcamp-costa-rica-2016\/","url_meta":{"origin":665,"position":4},"title":"Llamado a Sponsors #WCCR","author":"remediosgraphic","date":"August 28, 2016","format":false,"excerpt":"WordCamp Costa Rica 2016 se realizar\u00e1 en San Pedro el 5 y 6 de noviembre. La misma se llevar\u00e1 a cabo en las instalaciones de la Facultad de Microbiolog\u00eda de la UCR y contar\u00e1 con 3 tracks, User \/ Blogger \/ PM, UX Design, Developers (muy enfocado a javaScript). \u00a0\u2026","rel":"","context":"In &quot;news&quot;","block_context":{"text":"news","link":"https:\/\/sanjose.wordcamp.org\/2016\/category\/news\/"},"img":{"alt_text":"cr-town-wordcamp","src":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/08\/cr-town-wordcamp-1024x596.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/08\/cr-town-wordcamp-1024x596.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/08\/cr-town-wordcamp-1024x596.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":1470,"url":"https:\/\/sanjose.wordcamp.org\/2016\/racknation-se-une-al-wordcamp\/","url_meta":{"origin":665,"position":5},"title":"Racknation se une al WordCamp","author":"elpuas","date":"October 24, 2016","format":false,"excerpt":"Cuando las noticias son buenas, que puedan darnos muchas m\u00e1s. Hacer un WordCamp no es tarea f\u00e1cil pero con la ayuda de tantas personas las cosas fluyen, el caso es que algunas empresas se suman al evento m\u00e1s importante de WordPress en Costa Rica, hoy Racknation nos ofrece un 20%\u2026","rel":"","context":"In &quot;news&quot;","block_context":{"text":"news","link":"https:\/\/sanjose.wordcamp.org\/2016\/category\/news\/"},"img":{"alt_text":"racknation","src":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/racknation-e1477331604156.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/racknation-e1477331604156.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/racknation-e1477331604156.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/2016.sanjose.wordcamp.org\/files\/2016\/10\/racknation-e1477331604156.jpg?resize=700%2C400 2x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/users\/319559"}],"replies":[{"embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/comments?post=665"}],"version-history":[{"count":7,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/665\/revisions"}],"predecessor-version":[{"id":674,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/posts\/665\/revisions\/674"}],"wp:attachment":[{"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/categories?post=665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sanjose.wordcamp.org\/2016\/wp-json\/wp\/v2\/tags?post=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}